{"id":9489,"date":"2023-11-05T07:42:54","date_gmt":"2023-11-05T07:42:54","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/"},"modified":"2023-11-05T07:42:54","modified_gmt":"2023-11-05T07:42:54","slug":"amor-verdadero","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/","title":{"rendered":"Amor verdadero"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>Lo buscamos en pel\u00edculas como <i>Titanic <\/i>o <i>Memorias de \u00c1frica<\/i>, en historias de ficci\u00f3n que van desde Romeo y Julieta a la saga de los Bridgerton. <b>Perseguimos el reflejo del amor verdadero en esas historias rom\u00e1nticas y ficticias m\u00e1s grandes que la vida<\/b> que nos colocan en p\u00e1ginas y pantallas y olvidamos mirar d\u00f3nde realmente reside el m\u00e1ximo exponente de ese sentimiento: a nuestro alrededor, en la cotidianidad de aquellos que cuidan con entrega y desinteresadamente a sus hijos, parejas o padres, personas a las que la vida, que es caos, ha tra\u00eddo accidentes o enfermedades tan crueles como el <a href=\"https:\/\/www.20minutos.es\/minuteca\/cancer\/\" title=\"C\u00e1ncer\">c\u00e1ncer<\/a>, el da\u00f1o cerebral adquirido o propio de la edad o el <a href=\"https:\/\/www.20minutos.es\/minuteca\/autismo\/\" title=\"Autismo\">autismo<\/a> que incapacita. <b>Amor de verdad<\/b>.<\/p>\n<p>Esa anciana que acude a diario al hospital de rehabilitaci\u00f3n, a una hora de distancia de su casa, para estar con su marido a\u00fan m\u00e1s anciano que ella. La joven cuyo novio, igual de joven, tiene una enfermedad cr\u00f3nica que limita su existencia pero no el deseo que tienen de estar juntos tanto tiempo como la salud se lo permita. El padre que sale corriendo del trabajo para llevar a su hijo con <a href=\"https:\/\/www.20minutos.es\/minuteca\/discapacidad\/\" title=\"Discapacidad\">discapacidad<\/a> a la terapia que le toca, riendo con \u00e9l en el camino. La hija que se sienta con su padre todas las tardes, para recordarle su nombre y el de sus nietos y que tenga compa\u00f1\u00eda mientras aguarda la llegada del segador. <b>Historias reales todas ellas. Amor de verdad. <\/b><\/p>\n<p>Entre conflictos y pugnas por un poder que cuando la salud falla se antoja vac\u00edo, est\u00e1 bien volver la vista a todos esos cuidadores, cuyo amor resplandece como una estrella para guiarnos. El deseo de no ver el sufrimiento, la enfermedad y la muerte los eclipsa con demasiada frecuencia. Queremos deleitarnos con j\u00f3venes hermosos disfrutando de la vida, eso buscamos. Nos resistimos en cambio a observar al que cuida con cari\u00f1o y no \u00fanicamente por obligaci\u00f3n al mayor con <a href=\"https:\/\/www.20minutos.es\/minuteca\/alzheimer\/\" title=\"Alzh\u00e9imer\">alzh\u00e9imer<\/a> o al ni\u00f1o con <a href=\"https:\/\/www.20minutos.es\/minuteca\/paralisis-cerebral\/\" title=\"Par\u00e1lisis cerebral\">par\u00e1lisis cerebral<\/a>. <b>Y nos<\/b> <b>perdemos as\u00ed, al retirar la mirada, las historias de amor de verdad<\/b>.<\/p>\n<p>Hoy es el d\u00eda de los cuidadores, un buen d\u00eda para recordar que <b>el cuidar bien nos define y construye<\/b>, que somos animales que cuidan. Seguramente, tambi\u00e9n animales que <b>necesitaremos ser cuidados si llegamos a vivir lo suficiente. No lo olvidemos nunca.<\/b><\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5184631\/0\/amor-verdadero\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo buscamos en pel\u00edculas como Titanic o Memorias de \u00c1frica, en historias de ficci\u00f3n que van desde la saga de los Bridgerton a Romeo y Julieta. Perseguimos el reflejo del amor verdadero<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-9489","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Lo buscamos en pel\u00edculas como Titanic o Memorias de \u00c1frica, en historias de ficci\u00f3n que van desde la saga de los Bridgerton a Romeo y Julieta. Perseguimos el reflejo del amor verdadero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-05T07:42:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Amor verdadero\",\"datePublished\":\"2023-11-05T07:42:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/\"},\"wordCount\":430,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/\",\"name\":\"Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2023-11-05T07:42:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/05\\\/amor-verdadero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amor verdadero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/","og_locale":"es_ES","og_type":"article","og_title":"Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Lo buscamos en pel\u00edculas como Titanic o Memorias de \u00c1frica, en historias de ficci\u00f3n que van desde la saga de los Bridgerton a Romeo y Julieta. Perseguimos el reflejo del amor verdadero","og_url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2023-11-05T07:42:54+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Amor verdadero","datePublished":"2023-11-05T07:42:54+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/"},"wordCount":430,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/","url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/","name":"Amor verdadero - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2023-11-05T07:42:54+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/05\/amor-verdadero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Amor verdadero"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=9489"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9489\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=9489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=9489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=9489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}