{"id":9488,"date":"2023-11-04T07:49:19","date_gmt":"2023-11-04T07:49:19","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/"},"modified":"2023-11-04T07:49:19","modified_gmt":"2023-11-04T07:49:19","slug":"bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/","title":{"rendered":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \u00abBusco el oro en los segundos, pero sue\u00f1o con los primeros\u00bb"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p><b>Bruna Alexandre quiere romper barreras<\/b> y asegurarse una larga estancia en Par\u00eds el a\u00f1o pr\u00f3ximo. La jugadora de <a href=\"https:\/\/www.20minutos.es\/deportes\/minuteca\/tenis-de-mesa\/\" title=\"Tenis de mesa\">tenis de mesa<\/a>, que debut\u00f3 el jueves en los Juegos Panamericanos, <b>busca formar parte del equipo de Brasil tanto en los Juegos Ol\u00edmpicos y los Paraol\u00edmpicos<\/b> en Par\u00eds, algo que le mantendr\u00eda ocupada en <a href=\"https:\/\/www.20minutos.es\/minuteca\/francia\/\" title=\"Francia\">Francia<\/a> entre fines de julio e inicios de septiembre.<\/p>\n<p>Alexandre, de 28 a\u00f1os, <b>quiere incrementar el grupo de cinco deportistas que<\/b>, seg\u00fan el Comit\u00e9 Paraol\u00edmpico Internacional, <b>han participado en ambas competiciones en el mismo a\u00f1o<\/b>: la neozelandesa Neroli Fairhall (tiro con arco); el polaco Natalia Partyka (tenis de mesa); los sudafricanos Natalie du Toit (10 km en nado de aguas abiertas);  Oscar Pistorious (400 metros en atletismo); y la iran\u00ed Zarah Nemati (tiro con arco).<\/p>\n<p><b>Tercera en el ranking del tenis de mesa femenino en Brasil<\/b>, Alexandre ser\u00eda la primera deportista del continente americano que entrar\u00eda en ese exclusivo grupo si es convocada al equipo ol\u00edmpico. Ya sac\u00f3 su boleto para los <a href=\"https:\/\/www.20minutos.es\/deportes\/minuteca\/juegos-paralimpicos\/\" title=\"Juegos Paral\u00edmpicos\">Paraol\u00edmpicos<\/a>. <\/p>\n<p><b>Varios otros han competido en ambas justas, pero no en el mismo a\u00f1o<\/b>. La belga Sonia Vettenburg, una corredora en silla de ruedas tambi\u00e9n particip\u00f3 en tiro. Tambi\u00e9n est\u00e1n la tiradora Paola Fantato y la lanzadora de bala con discapacidad visual Assunta Legnante, ambas italianas. La otra es la estadounidense Marla Runyan, atleta con discapacidad visual.<\/p>\n<p>Alexandre cuenta que <b>nunca supo lo que era tener un brazo derecho: se lo amputaron cuando ten\u00eda tres meses de edad<\/b> por una trombosis. Siempre ha hecho lo que quiere y salir a donde quiere. <\/p>\n<p>\u201cSiempre he estado en la actividad deportiva en mi vida, f\u00fatbol bajo techo, skateboarding, ciclismo\u201d, dijo Alexandre a The Associated Press en Santiago esta semana. \u201cEmpec\u00e9 con el tenis de mesa a los siete meses, ya que mi hermano lo jugaba y ten\u00eda que llevarlo a casa\u00bb.<\/p>\n<p>Se encuentra entre las cinco mejores del mundo en el ranking paraol\u00edmpico, pero es la 220 en el escalaf\u00f3n ol\u00edmpico. <b>Tiene que estar entre las 80 mejores para clasificarse a los Juegos de Par\u00eds<\/b>. Al competir en el torneo femenino de equipos, Alexandre gan\u00f3 dos partidos de dobles junto a Giulia Takahashi para avanzar a los cuartos de final. <\/p>\n<p>Durante sus pr\u00e1cticas en Santiago, los analistas comentaron que Alexandre no tiene la misma movilidad de piernas como otras y su saque de un mano no es tan efectivo. Pero le pega fuerte y se defiende muy bien. <b>\u201cEstar en el equipo ol\u00edmpico me ayuda para competir con el Paral\u00edmpico\u201d<\/b>, dijo Alexandre \u201cEn los Paraol\u00edmpicos puedo sobrellevar y defender con m\u00e1s frecuencia. No lo puedo hacer en los Juegos Ol\u00edmpicos, tengo que atacar m\u00e1s, ser m\u00e1s r\u00e1pido y m\u00e1s activa\u201d.<\/p>\n<p><b>Lleva participando en disciplinas paraol\u00edmpicos desde que ten\u00eda 13 a\u00f1os<\/b>. Se mud\u00f3 de la ciudad sure\u00f1a de Criciuma a Sao Caetano cerca de Sao Paulo a los 16 a\u00f1os. Trabaja con el Comit\u00e9 Ol\u00edmpico de Brasil, que cuenta con uno de los pocos jugadores en el mundo, Hugo Calderano, capaces de desafiar a los mejores de China, la potencia del deporte.<\/p>\n<p>Alexandre ya h<b>a ganado una medalla de plata y dos bronces<\/b> en los Paraol\u00edmpicos en R\u00edo de Janeiro y Tokio. Aspira al oro en Francia con la ayuda de m\u00fasica brasile\u00f1a, series de televisi\u00f3n surcoreanas e inspiraci\u00f3n de los jugadores de China.<\/p>\n<h1>Quiero demostrar que todo es posible<\/h1>\n<p><b>\u201cBusco el oro en los Paral\u00edmpicos, pero sue\u00f1o con los Juegos Ol\u00edmpicos\u201d<\/b>, dijo. \u201cCuesta creer que pueda ser realidad. Tengo que trabajar en mi mentalidad para lograrlo. Muy pocos lo han logrado, llegar a los Juegos Ol\u00edmpicos es algo muy dif\u00edcil de conseguir para una persona como yo\u201d.<\/p>\n<p>El Comit\u00e9 Paraol\u00edmpico Internacional inform\u00f3 en un comunicado a The Associated Press que <b>es demasiado prematuro para adelantar que alg\u00fan atleta paraol\u00edmpico podr\u00e1 competir en ambas justas en Par\u00eds <\/b>y que se enfoca \u201c\u00fanicamente en que los atletas se destaquen en los Paraol\u00edmpicos\u201d.<\/p>\n<p>Alexandre tiene bien claro lo que quiere en Chile: \u201cQuiero demostrar que toda persona con discapacidad puede hacer cualquier cosa. <b>Quiero que se vea mi imagen compitiendo en unos Juegos Ol\u00edmpicos alg\u00fan d\u00eda<\/b>\u201d, dijo. \u201cEsa ser\u00eda una gran imagen para cualquier persona con una discapacidad, no s\u00f3lo en Brasil. Quiero demostrar que todo es posible\u201d.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5187082\/0\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bruna Alexandre quiere romper barreras y asegurar una larga estad\u00eda en Par\u00eds el a\u00f1o pr\u00f3ximo.La jugadora de tenis de mesa, que debuta el jueves en los Juegos Panamericanos, busca &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-9488","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: &quot;Busco el oro en los segundos, pero sue\u00f1o con los primeros&quot; - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: &quot;Busco el oro en los segundos, pero sue\u00f1o con los primeros&quot; - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Bruna Alexandre quiere romper barreras y asegurar una larga estad\u00eda en Par\u00eds el a\u00f1o pr\u00f3ximo.La jugadora de tenis de mesa, que debuta el jueves en los Juegos Panamericanos, busca &#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-04T07:49:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \u00abBusco el oro en los segundos, pero sue\u00f1o con los primeros\u00bb\",\"datePublished\":\"2023-11-04T07:49:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/\"},\"wordCount\":800,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/\",\"name\":\"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \\\"Busco el oro en los segundos, pero sue\u00f1o con los primeros\\\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2023-11-04T07:49:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: &#8220;Busco el oro en los segundos, pero sue\u00f1o con los primeros&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \"Busco el oro en los segundos, pero sue\u00f1o con los primeros\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/","og_locale":"es_ES","og_type":"article","og_title":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \"Busco el oro en los segundos, pero sue\u00f1o con los primeros\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Bruna Alexandre quiere romper barreras y asegurar una larga estad\u00eda en Par\u00eds el a\u00f1o pr\u00f3ximo.La jugadora de tenis de mesa, que debuta el jueves en los Juegos Panamericanos, busca &#8230;","og_url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2023-11-04T07:49:19+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \u00abBusco el oro en los segundos, pero sue\u00f1o con los primeros\u00bb","datePublished":"2023-11-04T07:49:19+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/"},"wordCount":800,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/","url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/","name":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: \"Busco el oro en los segundos, pero sue\u00f1o con los primeros\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2023-11-04T07:49:19+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/bruna-alexandre-brasilena-con-un-brazo-que-busca-competir-juegos-olimpicos-paraolimpicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Bruna Alexandre y el reto de ir a los Juegos Ol\u00edmpicos y Paraol\u00edmpicos: &#8220;Busco el oro en los segundos, pero sue\u00f1o con los primeros&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=9488"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9488\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=9488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=9488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=9488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}