{"id":9487,"date":"2023-11-04T07:49:06","date_gmt":"2023-11-04T07:49:06","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/"},"modified":"2023-11-04T07:49:06","modified_gmt":"2023-11-04T07:49:06","slug":"asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/","title":{"rendered":"\u00ab&#8216;Viejos&#8217; para trabajar, j\u00f3venes para jubilarse\u00bb, Asindown inaugura un centro especializado de envejecimiento para personas con Down"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>La Fundaci\u00f3n Asindown, una entidad que ofrece recursos y ayuda a personas con s\u00edndrome de Down o discapacidad intelectual desde hace 35 a\u00f1os, acaba de inaugurar \u00ab<b>Vida Adulta y Envejecimiento Activo<\/b>\u00ab, un centro, el primero a nivel nacional, con programas de Prevenci\u00f3n, Mantenimiento e Intervenci\u00f3n espec\u00edficos para personas con <a href=\"https:\/\/www.20minutos.es\/minuteca\/sindrome-de-down\/\" title=\"S\u00edndrome de Down\" target=\"_blank\" rel=\"noopener\">s\u00edndrome de Down<\/a> y s\u00edntomas de deterioro cognitivo.<\/p>\n<p>Desde hace cuatro a\u00f1os, ya dispon\u00edan de un programa de prevenci\u00f3n de envejecimiento dentro de su centro terap\u00e9utico, pero hace un a\u00f1o vieron la necesidad de abordar este tema m\u00e1s en profundidad, \u00abempezamos a pensarlo hace un a\u00f1o y llevamos trabajando en \u00e9l desde septiembre, aunque lo inauguramos el 3 de noviembre\u00bb, explica Mabel M\u00ednguez, coordinadora del centro.<\/p>\n<p>El motivo de ampliar la atenci\u00f3n al envejecimiento de personas con s\u00edndrome de Down es que, desde hace unos a\u00f1os, notaron que se empezaban a enfrentar a una nueva problem\u00e1tica, \u00abdesde Asindown llevamos m\u00e1s de 35 a\u00f1os trabajando para la integraci\u00f3n de las personas con s\u00edndrome de Down y <a href=\"https:\/\/www.20minutos.es\/minuteca\/discapacidad-intelectual\/\" title=\"Discapacidad intelectual\" target=\"_blank\" rel=\"noopener\">discapacidad intelectual<\/a>, y lo abordamos, sobre todo, form\u00e1ndolos para que trabajaran\u00bb.<\/p>\n<p>Tras conseguir que muchos de ellos trabajaran, pensaron que \u00abestaba todo hecho. Sin embargo, lleg\u00f3 un momento en que las empresas comenzaron a decirnos que empezaban a tener problemas, que ya no trabajaban como antes, que se desorientaban\u2026 y <b>ten\u00edan que dejar de trabajar<\/b>. Nos dimos cuenta de que esta problem\u00e1tica empezaba cuando ten\u00edan 35-40 a\u00f1os, y de que, adem\u00e1s, no ten\u00edamos nada creado para atender a esas personas\u00bb.<\/p>\n<p>Paralelamente, empezaron a aparecer estudios que afirmaban que todas las personas con s\u00edndrome de Down tienen un<b> envejecimiento prematuro<\/b>, que les provoca un deterioro cognitivo y un riesgo muy alto de que desarrollar demencias, \u00abfue entonces cuando empezamos a pensar c\u00f3mo ayudar a estas personas, ya sea buscando o creando un recurso propio. Cuando buscamos un recurso p\u00fablico, nos dimos cuenta de que no ten\u00edan acceso, porque tanto las residencias como los centros de d\u00eda exigen un requisito de edad, que son los 65 a\u00f1os. Pero nuestros usuarios lo necesitan mucho antes, as\u00ed que no nos qued\u00f3 otra que buscar alternativas y atenderlos nosotros\u00bb.<\/p>\n<p>En la actualidad,<b> atienden de 45 personas<\/b>, algunas de ellas todav\u00eda trabajando y otras, como Amparo Palmero, forman parte del centro y acuden a diario de 9 a 17 para hacer m\u00faltiples actividades destinadas a retrasar su envejecimiento prematuro y mejorar su calidad de vida.<\/p>\n<h1>Las personas con s\u00edndrome de Down experimentan un envejecimiento prematuro a partir de los 35-40 a\u00f1os<\/h1>\n<h2>\u2018Viejos\u2019 para trabajar, j\u00f3venes para jubilarse<\/h2>\n<p>Las <a href=\"https:\/\/www.20minutos.es\/noticia\/5128242\/0\/asi-se-podran-prejubilar-las-personas-con-una-discapacidad-igual-o-superior-al-45\/\" target=\"_blank\" rel=\"noopener\">personas con discapacidad pueden jubilarse de manera anticipada -a partir de los 56 o de los 52<\/a>-, si cumplen una serie de requisitos en cuanto a porcentaje de discapacidad y a\u00f1os cotizados. Sin embargo, en muchos casos, las personas con s\u00edndrome de Down desarrollan s\u00edntomas que les impiden trabajar a partir de los 35-40 a\u00f1os, \u00abnos encontramos con la problem\u00e1tica de que personas con una edad menor a la edad de jubilaci\u00f3n tienen que dejar de trabajar, una salida laboral que no tienen nada f\u00e1cil, ya que no se pueden jubilar al menos hasta los 52\u2026\u00bb, explica.<\/p>\n<p>Este es el caso de Amparo, que tras 24 a\u00f1os trabajando en ferrocarriles de la Comunidad Valenciana, tuvo que dejarlo el a\u00f1o pasado, \u00abhe estado trabajando desde los 20 a\u00f1os de ordenanza, auxiliar y repartiendo la correspondencia, pero ya no pod\u00eda m\u00e1s, estaba muy cansada\u00bb, nos cuenta.<\/p>\n<p>Amparo, como asegura Mabel, a\u00fan est\u00e1 muy bien, incluso va sola al centro en dos autobuses y le acompa\u00f1a a charlas, pero no tanto como para trabajar, \u00aben la actualidad est\u00e1 de baja temporal, y est\u00e1 a la espera de que le den la <b>incapacidad permanente<\/b>. Es la \u00fanica forma que tenemos de que estas personas mantengan su poder adquisitivo, porque si los mandan al paro la protecci\u00f3n ser\u00eda menor, y no pueden cogerse una baja voluntaria porque perder\u00edan sus derechos. Tenemos que luchar por la incapacidad hasta que tengan edad de jubilarse porque, por lo general, suelen faltarles varios a\u00f1os todav\u00eda\u00bb.<\/p>\n<p>Precisamente para personas como Amparo est\u00e1 pensado este recurso, destinado a<b> prevenir, mantener, intervenir <\/b>y ofrecer orientaci\u00f3n espec\u00edfica e individualizada para personas con s\u00edndrome de Down con envejecimiento prematuro.<\/p>\n<p>En este programa, en la actualidad <b>hay 18 personas que acuden de lunes a viernes, de 9 a 17<\/b>, a hacer multitud de actividades, \u00abprimero les hacemos una evaluaci\u00f3n neuropsicol\u00f3gica para ver si cumplen los requisitos para entrar, y despu\u00e9s les ofrecemos distintas actividades que sabemos, por los estudios cient\u00edficos que hay, que ayudan a mantener sus habilidades cognitivas, emocionales y sociales\u00bb. <\/p>\n<p>Amparo, nos enumera algunas de ellas, como \u00ab<b>fisioterapia en el agua, estimulaci\u00f3n cognitiva, talleres sensoriales<\/b>, deportes, ejercicio, cocina, musicoterapia, yoga, juegos de mesa, participaci\u00f3n social, salidas culturales\u2026\u00bb, incluso disponen de un taller olfativo porque, como explica la coordinadora del centro, est\u00e1 demostrado que les ayuda a mejorar la memoria, \u00abvamos trabajando un poco en funci\u00f3n de las investigaciones que van saliendo, y las \u00faltimas investigaciones nos dicen que trabajar <b>habilidades cognitivas, sociales y emocionales <\/b>permite mantener o retrasar los s\u00edntomas del envejecimiento prematuro y de la demencia. No se recupera, pero s\u00ed que permite alargar y conservar m\u00e1s tiempo sus capacidades\u00bb. <\/p>\n<h1>Nos encontramos con que personas con una edad mucho menor a la edad de jubilaci\u00f3n -entre los 35 y los 40 a\u00f1os- tienen que dejar de trabajar, y esa salida laboral no es f\u00e1cil <\/h1>\n<p>Esta problem\u00e1tica es relativamente nueva, pues, hasta hace unos 40 a\u00f1os, las personas con s\u00edndrome de Down <b>no viv\u00edan m\u00e1s all\u00e1 de los 45 a\u00f1os<\/b>. Ahora, gracias a la medicina, su vida se ha alargado casi 20 a\u00f1os, y el reto es que esos a\u00f1os vayan acompa\u00f1ados de calidad de vida, \u00abcuando viven con sus padres y dejan de trabajar, dejan de socializar, tienen a una vida m\u00e1s sedentaria\u2026 y este envejecimiento se acent\u00faa. Con este programa, buscamos lo contrario, que socialicen, coman bien, hagan ejercicio, actividades\u2026 y conseguimos retrasar este proceso\u00bb. <\/p>\n<p>\u00abEste a\u00f1o, adem\u00e1s, estamos haciendo una investigaci\u00f3n para medir indicadores que nos confirmen que, efectivamente, a nivel emocional, de habilidades sociales y de habilidades cognitivas se mantienen sus capacidades e incluso mejoran\u00bb, explica Mabel M\u00ednguez.<\/p>\n<h2>Alargar la vida laboral y un bonito proyecto de futuro<\/h2>\n<p>Adem\u00e1s de atender a las personas que han tenido que dejar de trabajar debido al envejecimiento prematuro, este programa tambi\u00e9n est\u00e1 destinado a que las personas que todav\u00eda est\u00e1n trabajando puedan <b>alargar su vida laboral<\/b> lo m\u00e1s posible, \u00aben la actualidad, hay 140 personas de Asindown que est\u00e1n trabajando, as\u00ed que tenemos que estar preparados. Por un lado, para ofrecerles un recurso al que ir despu\u00e9s, y por otro, tenemos que intentar alargar su vida laboral\u00bb.<\/p>\n<p>Por eso, adem\u00e1s de las personas con acuden al centro de 9 a 17 a diario, hay<b> otras 27<\/b> a las que ya est\u00e1 atendiendo, pero con un programa distinto, \u00abse trata de un programa preventivo dirigido a personas de 35 o m\u00e1s que ya muestran alg\u00fan s\u00edntoma, pero que <b>a\u00fan est\u00e1n trabajando<\/b>. Por un lado, estamos en contacto directo con sus medidores, empresas, familias\u2026 para ver c\u00f3mo evolucionan, y por otro, los atendemos con actividades, estimulaci\u00f3n\u2026 para retrasar ese deterioro prematura y poder alargar su vida laboral\u00bb. <\/p>\n<p>As\u00ed, en el momento en el que ya no puedan trabajar, pasar\u00e1n directamente al centro, y empezar\u00e1n a tramitar bajas, incapacidad, etc., \u00abAsindown empieza a atender a las familias desde que saben que va a nacer una persona con s\u00edndrome de Down\u2026 y si les estamos acompa\u00f1ando en todas sus etapas vitales, no ten\u00eda sentido dejar de atenderles cuando dejaran de trabajar, ten\u00edamos que <b>seguir atendiendo el resto de etapas\u00bb<\/b>, asegura la coordinadora, \u00abnuestra previsi\u00f3n es que m\u00e1s personas entren en el centro, as\u00ed que tenemos que estar preparados para crecer y buscar ayudas y conciertos p\u00fablicos, porque ahora lo hacemos todo de forma privada, aunque tengamos ayudas\u00bb, recuerda.<\/p>\n<h1>Los atendemos con distintas actividades y estimulaci\u00f3n para retrasar ese deterioro prematura y poder alargar su vida laboral <\/h1>\n<p>Adem\u00e1s, ya tienen en mente el que ser\u00e1 su pr\u00f3ximo gran proyecto, una especie de centro o residencial que no solo atienda a las personas con esta condici\u00f3n, sino tambi\u00e9n a sus familias, \u00abnos hemos fijado en un proyecto en Francia muy chulo, que es <b>una residencia donde comparten espacio padres e hijos<\/b>, que es un poco el objetivo a largo plazo de Asindown, llegar a crear este centro de convivencia\u00bb. <\/p>\n<p>Se trata de un proyecto muy a largo plazo en el que familiares y personas con Down pudieran seguir viviendo juntos cuando ambos tengan grandes necesidades de apoyo, pero con actividades separadas para ofrecer a cada colectivo lo que necesite, \u00abpor un lado, atender\u00edamos a las personas con s\u00edndrome de Down, con actividades adaptadas a sus necesidades, y por otro, a sus familias. Ambos estar\u00edan atendidos,<b> las familias tendr\u00edan un respiro, pero seguir\u00edan conviviendo juntos<\/b>\u00ab, aseguran.<\/p>\n<p>Desde Asindown ya trabajan para hacer realidad este id\u00edlico lugar, pero para llevarlo a cabo necesitan la ayuda de todos los agentes sociales, especialmente de los poderes p\u00fablicos.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5186820\/0\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El centro &#8216;Vida Adulta y Envejecimiento Activo&#8217; est\u00e1 dirigido a personas con s\u00edndrome de Down con signos de envejecimiento prematuro.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-9487","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;&#039;Viejos&#039; para trabajar, j\u00f3venes para jubilarse&quot;, Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;&#039;Viejos&#039; para trabajar, j\u00f3venes para jubilarse&quot;, Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"El centro &#8216;Vida Adulta y Envejecimiento Activo&#8217; est\u00e1 dirigido a personas con s\u00edndrome de Down con signos de envejecimiento prematuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-04T07:49:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"\u00ab&#8216;Viejos&#8217; para trabajar, j\u00f3venes para jubilarse\u00bb, Asindown inaugura un centro especializado de envejecimiento para personas con Down\",\"datePublished\":\"2023-11-04T07:49:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/\"},\"wordCount\":1632,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/\",\"name\":\"\\\"'Viejos' para trabajar, j\u00f3venes para jubilarse\\\", Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2023-11-04T07:49:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2023\\\/11\\\/04\\\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;&#8216;Viejos&#8217; para trabajar, j\u00f3venes para jubilarse&#8221;, Asindown inaugura un centro especializado de envejecimiento para personas con Down\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"'Viejos' para trabajar, j\u00f3venes para jubilarse\", Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/","og_locale":"es_ES","og_type":"article","og_title":"\"'Viejos' para trabajar, j\u00f3venes para jubilarse\", Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"El centro &#8216;Vida Adulta y Envejecimiento Activo&#8217; est\u00e1 dirigido a personas con s\u00edndrome de Down con signos de envejecimiento prematuro.","og_url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2023-11-04T07:49:06+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"\u00ab&#8216;Viejos&#8217; para trabajar, j\u00f3venes para jubilarse\u00bb, Asindown inaugura un centro especializado de envejecimiento para personas con Down","datePublished":"2023-11-04T07:49:06+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/"},"wordCount":1632,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/","url":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/","name":"\"'Viejos' para trabajar, j\u00f3venes para jubilarse\", Asindown inaugura un centro especializado de envejecimiento para personas con Down - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2023-11-04T07:49:06+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2023\/11\/04\/asindown-presenta-un-centro-envejecimiento-para-personas-con-sindrome-down\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"&#8220;&#8216;Viejos&#8217; para trabajar, j\u00f3venes para jubilarse&#8221;, Asindown inaugura un centro especializado de envejecimiento para personas con Down"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=9487"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/9487\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=9487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=9487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=9487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}