{"id":7451,"date":"2021-06-26T06:29:43","date_gmt":"2021-06-26T06:29:43","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/"},"modified":"2021-06-26T06:29:43","modified_gmt":"2021-06-26T06:29:43","slug":"index-php-5","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/","title":{"rendered":"27 de junio: D\u00eda Internacional de las Personas Sordociegas"},"content":{"rendered":"<p>Leemos en Federaci\u00f3n de Asociaciones de Implantados Cocleares de Espa\u00f1a. Federaci\u00f3n AICE la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p style=\"text-align: center;\"><strong>\u201cEl implante coclear me ha permitido reemprender la vida donde la diablesa gen\u00e9tica pretendi\u00f3 dejarme\u201d<\/strong><\/p>\n<p>El 27 de junio se celebra el d\u00eda Internacional de las personas sordociegas con la finalidad de dar visibilidad a todo este colectivo de personas que presentan esta discapacidad. Adem\u00e1s, se pretende sensibilizar al resto de la sociedad para que brinden su ayuda y puedan mejorar su calidad de vida.<\/p>\n<p>En honor a este d\u00eda tan especial hemos querido aportar nuestro granito de arena realizando una entrevista a Jordi Blesa Montoliu, implantado coclear, actor, dramaturgo, locutor y m\u00fasico que naci\u00f3 ciego y poco a poco fue perdiendo la audici\u00f3n debido a una enfermedad degenerativa llamada \u201cS\u00edndrome de Norrie\u201d.<\/p>\n<p>Jordi Blesa lleva dos implantes cocleares y nos ha contado c\u00f3mo fue perdiendo la audici\u00f3n a lo largo de los a\u00f1os, qu\u00e9 remedios utiliz\u00f3 para paliar esta discapacidad y c\u00f3mo el implante coclear le permiti\u00f3 volver a disfrutar de una de sus grandes pasiones, tocar el acorde\u00f3n.<\/p>\n<p>La sordoceguera es una discapacidad cong\u00e9nita que afecta tanto a la audici\u00f3n como a la visi\u00f3n de forma severa lo que provoca una limitaci\u00f3n considerable a aquellas personas que la padecen.<\/p>\n<p>Este d\u00eda sirve adem\u00e1s como homenaje a Hellen Keller, exitosa mujer que dio a conocer por todo el mundo la existencia de esta discapacidad. Nacida un 27 de junio de 1880 logr\u00f3 convertirse en la primera mujer sordociega de la historia en culminar una carrera universitaria. En Espa\u00f1a hay 1.327 implantados cocleares con problemas de visi\u00f3n. <strong><br \/><\/strong><\/p>\n<p>Descubre el v\u00eddeo completo sobre la historia de Jordi Blesa en:<\/p>\n<p><strong><a target=\"_blank\" href=\"https:\/\/aicpv.implantecoclear.org\/\" rel=\"noopener\">https:\/\/aicpv.implantecoclear.org<\/a> <\/strong><\/p>\n<\/div>\n<p>Fuente: Federaci\u00f3n de Asociaciones de Implantados Cocleares de Espa\u00f1a. Federaci\u00f3n AICE http:\/\/implantecoclear.org\/index.php?option=com_content&#038;view=article&#038;id=627:2021-06-28-06-34-01&#038;catid=1:latest-news<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEl implante coclear me ha permitido reemprender la vida donde la diablesa gen\u00e9tica pretendi\u00f3 dejarme\u201d El 27 de junio se celebra el d\u00eda Internacional de las personas sordociegas con la finalidad de dar visibilidad a todo este colectivo de personas que presentan esta discapacidad. Adem\u00e1s, se pretende sensibilizar al resto de la sociedad para que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-7451","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"\u201cEl implante coclear me ha permitido reemprender la vida donde la diablesa gen\u00e9tica pretendi\u00f3 dejarme\u201d El 27 de junio se celebra el d\u00eda Internacional de las personas sordociegas con la finalidad de dar visibilidad a todo este colectivo de personas que presentan esta discapacidad. Adem\u00e1s, se pretende sensibilizar al resto de la sociedad para que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-26T06:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"27 de junio: D\u00eda Internacional de las Personas Sordociegas\",\"datePublished\":\"2021-06-26T06:29:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/\"},\"wordCount\":344,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/\",\"name\":\"27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2021-06-26T06:29:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/26\\\/index-php-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"27 de junio: D\u00eda Internacional de las Personas Sordociegas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/","og_locale":"es_ES","og_type":"article","og_title":"27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"\u201cEl implante coclear me ha permitido reemprender la vida donde la diablesa gen\u00e9tica pretendi\u00f3 dejarme\u201d El 27 de junio se celebra el d\u00eda Internacional de las personas sordociegas con la finalidad de dar visibilidad a todo este colectivo de personas que presentan esta discapacidad. Adem\u00e1s, se pretende sensibilizar al resto de la sociedad para que [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2021-06-26T06:29:43+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"27 de junio: D\u00eda Internacional de las Personas Sordociegas","datePublished":"2021-06-26T06:29:43+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/"},"wordCount":344,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/","url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/","name":"27 de junio: D\u00eda Internacional de las Personas Sordociegas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2021-06-26T06:29:43+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/26\/index-php-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"27 de junio: D\u00eda Internacional de las Personas Sordociegas"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=7451"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7451\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=7451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=7451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=7451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}