{"id":7362,"date":"2021-06-30T16:24:45","date_gmt":"2021-06-30T16:24:45","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/"},"modified":"2021-06-30T16:24:45","modified_gmt":"2021-06-30T16:24:45","slug":"futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/","title":{"rendered":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>En concreto, y seg\u00fan ha informado Futuro Singular, el motivo alegado por la Junta es que \u00abse deniega el concierto educativo, para las unidades que se indican, por no ser necesarias para garantizar la continuidad del alumnado escolarizado en unidades sostenidas con fondos p\u00fablicos del centro\u00bb.<\/p>\n<p>Esta argumentaci\u00f3n, seg\u00fan ha explicado desde Futuro Singular, \u00abhace referencia a que hay menos alumnos, pero no contempla que los perfiles de los ni\u00f1os que asisten actualmente a los centros espec\u00edficos distan mucho de los de hace a\u00f1os, cuando se establecieron las ratios, que a\u00fan se mantienen\u00bb.<\/p>\n<p>As\u00ed, \u00aben la actualidad la mayor\u00eda del alumnado presenta altas necesidades de apoyo y dificultades de conducta, acompa\u00f1ado en muchos casos de graves problemas de salud\u00bb, y desde la Fundaci\u00f3n \u00abse hicieron estos planteamientos, tanto en las alegaciones presentadas, como en una reuni\u00f3n espec\u00edfica para ello con la delegada de C\u00f3rdoba, d\u00f3nde qued\u00f3 patente que la Fundaci\u00f3n realiza importantes esfuerzos econ\u00f3micos para dar repuesta a estas necesidades, que la administraci\u00f3n no asume\u00bb.<\/p>\n<p>A juicio de Futuro Singular, \u00abeste cierre no se produce por una reconversi\u00f3n de los centros educativos espec\u00edficos en centros de recursos que acompa\u00f1en a un modelo inclusivo, con lo que podr\u00edamos estar de acuerdo si se hiciese bien, sino por un mero recorte econ\u00f3mico\u00bb.<\/p>\n<p>La sensibilidad de las administraciones, \u00abauton\u00f3mica y estatal, hacia las personas con discapacidad intelectual, va quedando en evidencia una vez tras otra\u00bb, como \u00abhace unas semanas, con la rid\u00edcula actualizaci\u00f3n de precios de los servicios sociales que se present\u00f3, de un 2,6 por ciento, cuando se ha demostrado en reiteradas ocasiones que el desfase en los precios provocado en los \u00faltimos a\u00f1os supera el 25 por ciento, y ahora se suma el cierre de aulas en colegios espec\u00edficos\u00bb.<\/p>\n<p>Ante ello y desde Futuro Singular C\u00f3rdoba han anunciado que seguir\u00e1n \u00abluchando por los derechos de las personas con discapacidad intelectual, y por la adecuaci\u00f3n de los apoyos necesarios que \u00e9stas necesitan, a pesar de que las administraciones p\u00fablicas parecen no compartir este prop\u00f3sito\u00bb.<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4749323\/0\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/\" target=\"_blank\" rel=\"noopener\">Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: En concreto, y seg\u00fan ha informado Futuro Singular, el motivo alegado por la Junta es que \u00abse deniega el concierto educativo, para las unidades que se indican, por no ser necesarias para garantizar la continuidad del alumnado escolarizado en unidades sostenidas con fondos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-7362","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: En concreto, y seg\u00fan ha informado Futuro Singular, el motivo alegado por la Junta es que \u00abse deniega el concierto educativo, para las unidades que se indican, por no ser necesarias para garantizar la continuidad del alumnado escolarizado en unidades sostenidas con fondos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-30T16:24:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial\",\"datePublished\":\"2021-06-30T16:24:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/\"},\"wordCount\":409,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/\",\"name\":\"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2021-06-30T16:24:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/30\\\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/","og_locale":"es_ES","og_type":"article","og_title":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: En concreto, y seg\u00fan ha informado Futuro Singular, el motivo alegado por la Junta es que \u00abse deniega el concierto educativo, para las unidades que se indican, por no ser necesarias para garantizar la continuidad del alumnado escolarizado en unidades sostenidas con fondos [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2021-06-30T16:24:45+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial","datePublished":"2021-06-30T16:24:45+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/"},"wordCount":409,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/","url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/","name":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2021-06-30T16:24:45+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/30\/futuro-singular-critica-que-la-junta-retira-el-concierto-a-dos-aulas-de-educacion-especial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Futuro Singular critica que la Junta retira el concierto a dos aulas de Educaci\u00f3n Especial"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=7362"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7362\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=7362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=7362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=7362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}