{"id":7349,"date":"2021-06-28T15:38:05","date_gmt":"2021-06-28T15:38:05","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/"},"modified":"2021-06-28T15:38:05","modified_gmt":"2021-06-28T15:38:05","slug":"andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/","title":{"rendered":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>El Gobierno de La Rioja, a trav\u00e9s de la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica, ha organizado este acto con el fin de reconocer la labor y entrega de profesionales y voluntarios durante los peores meses de pandemia.<\/p>\n<p>As\u00ed, han estado presentes los doce directores de los Centros de Participaci\u00f3n Activa de personas mayores de La Rioja; los doce presidentes de las juntas de participaci\u00f3n de los Centros de Participaci\u00f3n Activa; los directores o representantes de los centros de d\u00eda; los presidentes de LARES y ARTE (asociaciones que aglutinan a las residencias de personas mayores con y sin \u00e1nimo de lucro); dos voluntarios de los centros de participaci\u00f3n activa de Arnedo y Autol; representantes del Consejo Sectorial de Personas Mayores: la directora de la residencia p\u00fablica de personas mayores de Lardero, Raquel Alvero, y la supervisora de la de Calahorra, Ana Rosa Jim\u00e9nez.<\/p>\n<p>Tambi\u00e9n  funcionarios de los servicios de mayores y de inspecci\u00f3n del Gobierno de La Rioja; el Servicio de Epidemiolog\u00eda del SERIS representado por su jefa de servicio, Eva Mart\u00ednez Ochoa, y el servicio de Enfermer\u00eda de Hospitalizaci\u00f3n a Domicilio representado por Yolanda Caro.<\/p>\n<p>La presidenta del Ejecutivo regional ha recordado los meses m\u00e1s duros de pandemia y su virulencia en unos de los sectores m\u00e1s castigados; las personas mayores. \u00abTen\u00edamos muy presente la deuda que todos tenemos con nuestros mayores, con los que nos han cuidado toda la vida, eran los m\u00e1s vulnerables y deb\u00edamos cuidar de ellos. Pero cuidar no solo significa cubrir necesidades b\u00e1sicas sanitarias o econ\u00f3micas, cuidar significa que tambi\u00e9n nos ocupemos de cubrir necesidades sociales, de ocio, culturales y socioafectivas.<\/p>\n<p>En La Rioja, la cifra de mayores de 65 a\u00f1os ha ido aumentando a lo largo de los \u00faltimos a\u00f1os, pasando del 18 por ciento en 2011 al 21 por ciento en 2020. Del total de personas mayores, un 5 por ciento vive en residencias y el 95 por ciento restante en sus domicilios.<\/p>\n<p>A lo largo de su intervenci\u00f3n, la presidenta del Ejecutivo regional ha destacado el \u00abcomportamiento ejemplar\u00bb de trabajadores, familiares y usuarios de residencias de personas mayores. \u00abHan sido uno meses duros, dur\u00edsimos durante los que hab\u00e9is hecho un esfuerzo enorme por cumplir las normas de seguridad e higiene\u00bb. Un tiempo durante el que el Ejecutivo regional ha adoptado una serie de medidas dirigidas a \u00absalvar vidas, medidas que inclu\u00edan dejar de ver a sus seres queridos durante demasiados meses, sin embargo, y a pesar de la crudeza de las mismas, su respuesta ha sido siempre ejemplar\u00bb.<\/p>\n<p>Un esfuerzo que desde el Ejecutivo regional deb\u00eda ser correspondido \u00aby por esta raz\u00f3n comenzamos a realizar pruebas diagn\u00f3sticas semanales porque con las residencias cerradas, los trabajadores eran la \u00fanica puerta de entrada al virus\u00bb.  Un total de 260.000 euros para la adquisici\u00f3n de 57.600 pruebas diagn\u00f3sticas para detectar trabajadores positivos asintom\u00e1ticos y evitar que el virus siguiera contagiando al resto de profesionales y usuarios.<\/p>\n<p>A finales de diciembre de 2020 comenz\u00f3 el proceso de vacunaci\u00f3n del colectivo m\u00e1s castigado por el virus. En estos momentos, todo el colectivo de personas mayores est\u00e1 ya vacunado y se ha comprobado que \u00ablas vacunas funcionan y son efectivas\u00bb. De hecho, ha recordado que las 33 residencias p\u00fablicas y privadas de La Rioja est\u00e1n libres de COVID-19 y desde hace cuatro meses no se ha registrado ning\u00fan fallecido por COVID-19 en ninguno de estos centros.<\/p>\n<p>175.000 EUROS PARA LA PROGRAMACI\u00d3N DE LOS CPA<\/p>\n<p>Asimismo, el acto organizado por la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica tambi\u00e9n ha querido reconocer a ese 95 por ciento de personas mayores que viven en sus domicilios. \u00abEllos tambi\u00e9n son h\u00e9roes y han sido escrupulosos en el cumplimiento de las normas de seguridad e higiene\u00bb, ha aseverado Andreu. \u00abAhora nos toca a nosotros hacer todo lo posible para que la normalidad vuelva tambi\u00e9n para ellos\u00bb.<\/p>\n<p>En este sentido, Andreu, ha recordado que \u00abel pr\u00f3ximo mes de octubre, el Centro de Participaci\u00f3n Activa de Lobete, y los otros once que hay distribuidos en La Rioja, se volver\u00e1n a llenar de personas con inquietudes y con ganas de seguir cumpliendo a\u00f1os y sue\u00f1os\u00bb. Y, para ello, el Ejecutivo regional ha reservado una partida de superior a los 175.000 euros para dise\u00f1ar los distintos cursos y actividades que \u00abvolver\u00e1n a llenar de vida los centros de participaci\u00f3n activa a partir del pr\u00f3ximo 15 de octubre\u00bb, fecha en la que volver\u00e1n las actividades presenciales a estos centros.<\/p>\n<p>Y es que, ha apostillado la presidenta del Gobierno de La Rioja, \u00abestas actividades favorecen la autonom\u00eda personal de los usuarios y la permanencia de estos en su propio entorno, as\u00ed como el mantenimiento de las relaciones sociales\u00bb.<\/p>\n<p>Y junto a los profesionales, familiares y usuarios de las residencias de personas mayores y centros de participaci\u00f3n activa, la l\u00edder del Ejecutivo regional tambi\u00e9n ha tenido un recuerdo para los usuarios y trabajadores de los centros de d\u00eda. \u00abRecursos que garantizan una atenci\u00f3n diurna a personas mayores con alg\u00fan grado de deterioro f\u00edsico o cognitivo, una atenci\u00f3n especializada y con una finalidad preventiva y rehabilitadora\u00bb. Pero, adem\u00e1s, Concha Andreu ha destacado el \u00abapoyo important\u00edsimo que suponen para las familias o cuidadores de estos usuarios, por esta raz\u00f3n, hoy tambi\u00e9n queremos daros las gracias por cuidar a los que cuidan\u00bb.<\/p>\n<p>En definitiva, ha concluido la presidenta del Gobierno de La Rioja, \u00abcon este acto, el Ejecutivo regional quiere daros las gracias por haberos dejado la piel durante al \u00faltimo a\u00f1o y medio por uno de los colectivos m\u00e1s vulnerables, gracias a las personas mayores por vuestros sacrificios, entereza y vuestro comportamiento ejemplar\u00bb.<\/p>\n<p>De cara al futuro, el reto del Ejecutivo regional, a trav\u00e9s de la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica es revisar el modelo de atenci\u00f3n a las personas mayores. De hecho, el consejero, Pablo Rubio, considera que \u00ablas residencias, siendo un recurso imprescindible en la actualidad para dar respuesta a las demandas ante situaciones de gran dependencia, deben ser el \u00faltimo recurso en su atenci\u00f3n, priorizando la participaci\u00f3n activa de las personas mayores, la teleasistencia y la ayuda a domicilio, los centros de d\u00eda y otras alternativas a la institucionalizaci\u00f3n, incluidos medidas de apoyo a las propias familias\u00bb.<\/p>\n<p>Asimismo, y una vez superados los meses m\u00e1s duros, Rubio ha reflexionado sobre la incidencia del virus en este colectivo. \u00abLa pandemia ha reflejado la necesidad de una mayor coordinaci\u00f3n entre la atenci\u00f3n social y la sanitaria a las personas mayores y las respuestas desde la atenci\u00f3n primaria ante la cronicidad en la hospitalizaci\u00f3n domiciliaria y en la media y larga estancia\u00bb.<\/p>\n<p>Por su parte la directora general de Dependencia, Discapacidad y Mayores, Mar\u00eda Somalo, ha reiterado el agradecimiento \u00aby reconocimiento por parte del Gobierno de La Rioja a todos los que trabajan en el sector, en el \u00e1mbito de las personas mayores por el trabajo realizado en la pandemia, por el que realizan habitualmente y por el que realizar\u00e1n en un futuro\u00bb. Asimismo, Somalo ha destacado la labor del equipo de la jefa de servicio de Epidemiolog\u00eda del SERIS, Eva Mart\u00ednez Ochoa, y del de Yolanda Caro en representaci\u00f3n del servicio de Enfermer\u00eda de Hospitalizaci\u00f3n a Domicilio por \u00absu sensibilidad y agilidad en la gesti\u00f3n de las pruebas diagn\u00f3sticas de las personas mayores en los centros de d\u00eda y residencias porque han sido determinantes y cruciales en el control de la pandemia dentro de este colectivo\u00bb.<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4746266\/0\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/\" target=\"_blank\" rel=\"noopener\">Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: El Gobierno de La Rioja, a trav\u00e9s de la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica, ha organizado este acto con el fin de reconocer la labor y entrega de profesionales y voluntarios durante los peores meses de pandemia. As\u00ed, han estado presentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-7349","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: El Gobierno de La Rioja, a trav\u00e9s de la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica, ha organizado este acto con el fin de reconocer la labor y entrega de profesionales y voluntarios durante los peores meses de pandemia. As\u00ed, han estado presentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T15:38:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia\",\"datePublished\":\"2021-06-28T15:38:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/\"},\"wordCount\":1349,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/\",\"name\":\"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2021-06-28T15:38:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/28\\\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/","og_locale":"es_ES","og_type":"article","og_title":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: El Gobierno de La Rioja, a trav\u00e9s de la Consejer\u00eda de Servicios Sociales y Gobernanza P\u00fablica, ha organizado este acto con el fin de reconocer la labor y entrega de profesionales y voluntarios durante los peores meses de pandemia. As\u00ed, han estado presentes [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2021-06-28T15:38:05+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia","datePublished":"2021-06-28T15:38:05+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/"},"wordCount":1349,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/","url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/","name":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2021-06-28T15:38:05+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/28\/andreu-agradece-el-comportamiento-ejemplar-de-las-personas-mayores-profesionales-y-voluntarios-en-la-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Andreu agradece el &quot;comportamiento ejemplar&quot; de las personas mayores, profesionales y voluntarios en la pandemia"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=7349"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7349\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=7349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=7349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=7349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}