{"id":7332,"date":"2021-06-23T12:04:45","date_gmt":"2021-06-23T12:04:45","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/"},"modified":"2021-06-23T12:04:45","modified_gmt":"2021-06-23T12:04:45","slug":"la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/","title":{"rendered":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>\u00abEs una de las noticias que m\u00e1s ganas ten\u00edamos de anunciar y que es posible gracias a los buenos resultados que est\u00e1 dando la vacunaci\u00f3n\u00bb, ha indicado Broto. Las vacunas han permitido controlar la situaci\u00f3n epidemiol\u00f3gica, que presenta tres brotes activos entre las 288 residencias de Arag\u00f3n, frente a los 43 de hace justo medio a\u00f1o, \u00abestamos viendo que no hay contagios\u00bb, ha a\u00f1adido.<\/p>\n<p>La consejera ha detallado que la nueva orden en la que se recoge esta medida se publicar\u00e1 en los pr\u00f3ximos d\u00edas en el Bolet\u00edn Oficial de Arag\u00f3n (BOA) y, desde ese momento, pasar\u00e1 a ser efectiva y podr\u00e1 aplicarse cuando los centros est\u00e9n preparados para ello.<\/p>\n<p>La novedad, seg\u00fan ha subrayado Mar\u00eda Victoria Broto, afecta \u00fanicamente a los residentes vacunados, que son quienes podr\u00e1n prescindir de las mascarillas \u00abdentro de sus hogares, que son las residencias\u00bb. Aquellos que no est\u00e9n vacunados, los trabajadores y los visitantes mantienen la obligatoriedad del uso de la mascarilla, al ser personas que entran y salen de este grupo de convivencia.<\/p>\n<p>Del mismo modo, la titular de Derechos Sociales ha querido precisar que esta novedad est\u00e1 pensada, s\u00f3lo, para las residencias, y no afecta a ning\u00fan otro centro de Servicios Sociales de la Comunidad.<\/p>\n<p>En este sentido, en una orden anterior ya se permiti\u00f3 la estancia sin mascarilla de los residentes vacunados en el exterior de los espacios privativos de las residencias, y se mantiene la obligatoriedad del control de aforo en la realizaci\u00f3n de actividades o servicio de comedor, con la distancia interpersonal de 1,5 metros.<\/p>\n<p>Adem\u00e1s, Broto ha apostillado que \u00abtodas las medidas y cambios seguir\u00e1n marcados por la vigilancia, la prudencia y el sentido com\u00fan en su aplicaci\u00f3n\u00bb.<\/p>\n<p>PASEOS CON VOLUNTARIOS<\/p>\n<p>La orden que recoge esta medida, permite que los voluntarios que acudan a los centros, con convenios y acuerdos de colaboraci\u00f3n, para acompa\u00f1ar a los mayores o personas con discapacidad en sus paseos y actividades, puedan retomar estas labores, siempre que est\u00e9n vacunados.<\/p>\n<p>\u00abEs una alegr\u00eda que pueda volver a producirse ese intercambio solidario que tanto bien hace a los mayores, que pueden salir a pasear acompa\u00f1ados, y a los voluntarios, que tambi\u00e9n aprenden y disfrutan con este v\u00ednculo tan especial que se crea\u00bb, ha dicho la consejera del Gobierno de Arag\u00f3n.<\/p>\n<p>Por su parte, la directora de la residencia de Borja, ha manifestado que \u00abnuestros centros son centros de convivencia, son hogares, pero sobretodo son centros llenos de vida\u00bb.<\/p>\n<p>\u00abEl \u00faltimo a\u00f1o ha estado marcado por el sufrimiento de trabajadores, usuarios y familias\u00bb, pero que la nueva situaci\u00f3n permite mirar hacia delante con la esperanza puesta en la vacunaci\u00f3n, ha sostenido Pe\u00f1a.<\/p>\n<p>En la residencia de Borja se han ido retomando, poco a poco, las actividades de ocio y convivencia que se realizaban antes de la pandemia, entre ellas, los paseos por el centro de Borja, las actividades de fisioterapia en el jard\u00edn y de terapia ocupacional.<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4740725\/0\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/\" target=\"_blank\" rel=\"noopener\">La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: \u00abEs una de las noticias que m\u00e1s ganas ten\u00edamos de anunciar y que es posible gracias a los buenos resultados que est\u00e1 dando la vacunaci\u00f3n\u00bb, ha indicado Broto. Las vacunas han permitido controlar la situaci\u00f3n epidemiol\u00f3gica, que presenta tres brotes activos entre las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-7332","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: \u00abEs una de las noticias que m\u00e1s ganas ten\u00edamos de anunciar y que es posible gracias a los buenos resultados que est\u00e1 dando la vacunaci\u00f3n\u00bb, ha indicado Broto. Las vacunas han permitido controlar la situaci\u00f3n epidemiol\u00f3gica, que presenta tres brotes activos entre las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T12:04:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados\",\"datePublished\":\"2021-06-23T12:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/\"},\"wordCount\":563,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/\",\"name\":\"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2021-06-23T12:04:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/","og_locale":"es_ES","og_type":"article","og_title":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: \u00abEs una de las noticias que m\u00e1s ganas ten\u00edamos de anunciar y que es posible gracias a los buenos resultados que est\u00e1 dando la vacunaci\u00f3n\u00bb, ha indicado Broto. Las vacunas han permitido controlar la situaci\u00f3n epidemiol\u00f3gica, que presenta tres brotes activos entre las [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2021-06-23T12:04:45+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados","datePublished":"2021-06-23T12:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/"},"wordCount":563,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/","url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/","name":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2021-06-23T12:04:45+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/la-mascarilla-deja-de-ser-obligatoria-para-los-residentes-vacunados-en-los-centros-de-mayores-y-discapacitados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"La mascarilla deja de ser obligatoria para los residentes vacunados en los centros de mayores y discapacitados"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=7332"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7332\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=7332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=7332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=7332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}