{"id":7330,"date":"2021-06-23T08:15:01","date_gmt":"2021-06-23T08:15:01","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/"},"modified":"2021-06-23T08:15:01","modified_gmt":"2021-06-23T08:15:01","slug":"en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/","title":{"rendered":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb"},"content":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p><p>Jon es un joven de 16 a\u00f1os reci\u00e9n vacunado. A pesar de que no le corresponde por edad, s\u00ed por riesgo, ya que \u00abtiene diagnosticada una posible enfermedad mitocondrial y confirmado un defecto gen\u00e9tico en el gen VAMP2, con el que se cree que no hay nadie m\u00e1s en Espa\u00f1a\u00bb explica su madre, Natividad.<\/p>\n<p>Desde su nacimiento notaron que algo no iba bien, pero no fue hasta los 3 a\u00f1os cuando les dijeron que podr\u00eda ser una enfermedad de este tipo. Diez a\u00f1os despu\u00e9s, con 13, y tras mucho pelear desde la familia para que no cerraran su caso, \u00abconseguimos un diagn\u00f3stico gen\u00e9tico de una mutaci\u00f3n que a\u00fan no estaba ni siquiera asociada a un cuadro cl\u00ednico\u00bb recuerda Natividad.<\/p>\n<p>De hecho, se sabe que en el mundo hay unos 8 casos con el de Jon, que tiene epilepsia, retraso severo psicomotriz y un problema muy grave de tr\u00e1nsito intestinal. La incertidumbre de la propia enfermedad rara, su origen y evoluci\u00f3n es incalculable, por eso, su madre reconoce que \u00aben enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio, ya tenemos suficientes preocupaciones\u00bb.<\/p>\n<p>Afortunadamente, tanto Jon como sus padres han recibido ya sus primeras dosis, siguiendo con los criterios de la Estrategia Nacional, pero tambi\u00e9n la auton\u00f3mica, donde tambi\u00e9n han constatado graves diferencias desde la familia.<\/p>\n<p>Mientras las vacunas llegaban, \u00abhemos tenido que anular terapias y de hecho, hasta septiembre no volvi\u00f3 al cole. Desde entonces adem\u00e1s llevamos sin ver a la familia por miedo y por garantizar la seguridad de proteger a Jon\u00bb reconoce su madre. De hecho, a d\u00eda de hoy contin\u00faan en semiconfinamiento, aunque reconoce que \u00abla vacuna nos ha vuelto a ilusionar de que este verano podamos volver al pueblo donde vive mi familia, ya con la tranquilidad de que mis padres est\u00e1n vacunados y nosotros tambi\u00e9n\u00bb.<\/p>\n<p>\u00daltima actualizaci\u00f3n 23\/06\/2021<\/p>\n<\/p>\n<p>Fuente: FEDER <a href=\"https:\/\/enfermedades-raras.org\/index.php\/actualidad\/noticias-eventos\/2-feder\/15555-%C2%ABen-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio%C2%BB\" target=\"_blank\" rel=\"noopener\">\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Jon es un joven de 16 a\u00f1os reci\u00e9n vacunado. A pesar de que no le corresponde por edad, s\u00ed por riesgo, ya que \u00abtiene diagnosticada una posible enfermedad mitocondrial y confirmado un defecto gen\u00e9tico en el gen VAMP2, con el que se cree [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[36],"class_list":["post-7330","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-enfermedades-raras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Jon es un joven de 16 a\u00f1os reci\u00e9n vacunado. A pesar de que no le corresponde por edad, s\u00ed por riesgo, ya que \u00abtiene diagnosticada una posible enfermedad mitocondrial y confirmado un defecto gen\u00e9tico en el gen VAMP2, con el que se cree [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T08:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb\",\"datePublished\":\"2021-06-23T08:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/\"},\"wordCount\":366,\"commentCount\":0,\"keywords\":[\"enfermedades raras\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/\",\"name\":\"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2021-06-23T08:15:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2021\\\/06\\\/23\\\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/","og_locale":"es_ES","og_type":"article","og_title":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Jon es un joven de 16 a\u00f1os reci\u00e9n vacunado. A pesar de que no le corresponde por edad, s\u00ed por riesgo, ya que \u00abtiene diagnosticada una posible enfermedad mitocondrial y confirmado un defecto gen\u00e9tico en el gen VAMP2, con el que se cree [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2021-06-23T08:15:01+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb","datePublished":"2021-06-23T08:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/"},"wordCount":366,"commentCount":0,"keywords":["enfermedades raras"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/","url":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/","name":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2021-06-23T08:15:01+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2021\/06\/23\/en-enfermedades-rara-son-podemos-arriesgarnos-a-conocer-el-impacto-de-un-contagio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"\u00abEn enfermedades rara son podemos arriesgarnos a conocer el impacto de un contagio\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=7330"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/7330\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=7330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=7330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=7330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}