{"id":5583,"date":"2020-04-28T11:48:31","date_gmt":"2020-04-28T11:48:31","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/"},"modified":"2020-04-28T11:48:31","modified_gmt":"2020-04-28T11:48:31","slug":"cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/","title":{"rendered":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.298 finados, 1.592 personas han perdido la vida en su residencia o centro (15 m\u00e1s que ayer) mientras que otras 706 han fallecido en el hospital (14 m\u00e1s que el lunes).<\/p>\n<p>En el caso concreto de los 1.228 fallecidos con COVID-19 confirmado, 641 han perdido la vida en el hospital frente a 587 que lo han hecho en sus centros de residencia; mientras que de los 1.070 finados con s\u00edntomas compatibles pr\u00e1cticamente la totalidad (1.005) ha muerto en el centro de residencia frente a 65 que han perdido la vida en el hospital.<\/p>\n<p>Por su parte y seg\u00fan los datos facilitados este lunes, 27 de abril, por el Gobierno auton\u00f3mico, el mayor n\u00famero de fallecidos por COVID-19 confirmado se registra de nuevo en Valladolid, con 247 casos, cinco m\u00e1s que ayer; seguida de Salamanca, con 205, dos m\u00e1s, y de Segovia, con 172 la misma cifra que ayer.<\/p>\n<p>En el caso de Le\u00f3n alcanza los 175 finados, once m\u00e1s que el lunes; Burgos 135, tres m\u00e1s; \u00c1vila suma cuatro m\u00e1s, hasta los 103; Soria, 97, tres m\u00e1s; Zamora, se mantiene en 49 y Palencia suma uno m\u00e1s, hasta los 45.<\/p>\n<p>Respecto a los fallecimientos con s\u00edntomas compatibles con el coronavirus, la mayor parte se registra en Salamanca, con 204 casos, uno menos que ayer, seguida de Segovia, con 203 casos, uno m\u00e1s que el lunes; Le\u00f3n suma uno, con 181; Valladolid se mantiene con 119 y Burgos registra 101, uno menos que el d\u00eda precedente.<\/p>\n<p>El resto de las provincias est\u00e1n por debajo del centenar de fallecidos con s\u00edntomas como Soria, con 87 (igual que los d\u00edas anteriores); \u00c1vila, tiene 79, uno menos; Zamora, sigue con 60 y Palencia suma uno hasta los 36.<\/p>\n<p>Adem\u00e1s, y seg\u00fan los datos facilitados por la Consejer\u00eda de Familia, de esos 1.214 centros analizados por la Junta se han registrado fallecidos en 260 residencias (se mantiene la cifra), 62 de ellos con un solo caso y 119 centros con m\u00e1s de cinco casos (dos m\u00e1s que ayer).<\/p>\n<p>Por su parte, los datos de contagios confirmados (personas a las que se les ha practicado la prueba del COVID-19 con resultado positivo) asciende a 5.396, es decir 46 m\u00e1s que ayer, de ellos 485 en \u00c1vila, 757 en Burgos, 805 en Le\u00f3n, 263 en Palencia, 702 en Salamanca, 566 en Segovia, 576 en Soria, 1.076 en Valladolid y 166 en Zamora.<\/p>\n<p>Finalmente, otras 881 personas permanecen aisladas con s\u00edntomas compatibles con COVID-19 (57 menos que este lunes), de ellos 92 en \u00c1vila, 71 en Burgos, 66 en Le\u00f3n, 66 en Palencia, 208 en Salamanca, 98 en Segovia, 56 en Soria, 163 en Valladolid y 61 en Zamora.<\/p>\n<p>En aislamiento preventivo pero sin s\u00edntomas hay otros 5.331 casos, 46 menos que ayer, de ellos 319 en \u00c1vila, 766 en Burgos, 702 en Le\u00f3n, 457 en Palencia, 900 en Salamanca, 530 en Segovia, 600 en Soria, 578 en Valladolid y 479 en Zamora.<\/p>\n<p>En total y seg\u00fan los datos aportados por la Junta, desde que comenz\u00f3 el estado de alarma en el pa\u00eds han perdido la vida en la comunidad 3.590 personas mayores \u00abpor cualquier causa\u00bb en estas residencias en las que residen 43.439 personas.<\/p>\n<p>TUTELADAS POR LA JUNTA<\/p>\n<p>Por \u00faltimo, en las 25 residencias que est\u00e1n tuteladas directamente por la Junta de Castilla y Le\u00f3n, y que acogen a 2.804 usuarios -se manetiene 54 residentes hospitalizados-, se han registrado 101 fallecidos confirmados por COVID-19, cinco m\u00e1s que ayer, mientras que 110 (tres m\u00e1s que ayer) han perdido la vida por s\u00edntomas relacionados con el coronavirus.<\/p>\n<p>Adem\u00e1s, 471 permanecen en las residencias con positivo confirmado; 85 personas est\u00e1n aisladas con s\u00edntomas compatibles con el COVID-19, frente a 94 del lunes, y 755 se encuentran en aislamiento preventivo sin s\u00edntomas, 168 m\u00e1s que el d\u00eda anterior.<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4240484\/0\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/\" target=\"_blank\" rel=\"noopener noreferrer\">CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.298 finados, 1.592 personas han perdido la vida en su residencia o centro (15 m\u00e1s que ayer) mientras que otras 706 han fallecido en el hospital (14 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-5583","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.298 finados, 1.592 personas han perdido la vida en su residencia o centro (15 m\u00e1s que ayer) mientras que otras 706 han fallecido en el hospital (14 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-28T11:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas\",\"datePublished\":\"2020-04-28T11:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/\"},\"wordCount\":656,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/\",\"name\":\"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2020-04-28T11:48:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/28\\\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/","og_locale":"es_ES","og_type":"article","og_title":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.298 finados, 1.592 personas han perdido la vida en su residencia o centro (15 m\u00e1s que ayer) mientras que otras 706 han fallecido en el hospital (14 [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2020-04-28T11:48:31+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas","datePublished":"2020-04-28T11:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/"},"wordCount":656,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/","url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/","name":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2020-04-28T11:48:31+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/28\/cyl-registra-2-298-fallecidos-en-residencias-29-mas-que-ayer-con-1-228-positivos-y-1-070-con-sintomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"CyL registra 2.298 fallecidos en residencias, 29 m\u00e1s que ayer, con 1.228 positivos y 1.070 con s\u00edntomas"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=5583"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5583\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=5583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=5583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=5583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}