{"id":5581,"date":"2020-04-27T14:49:42","date_gmt":"2020-04-27T14:49:42","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/"},"modified":"2020-04-27T14:49:42","modified_gmt":"2020-04-27T14:49:42","slug":"nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/","title":{"rendered":"Nuestras personas voluntarias env\u00edan un mensaje a las familias"},"content":{"rendered":"<p>Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Las <a href=\"https:\/\/www.menudoscorazones.org\/colabora\/voluntariado\/\">personas voluntarias<\/a> de la Fundaci\u00f3n tambi\u00e9n han visto su importante labor\u00a0afectada por el coronavirus. A pesar de ello, \u00a1su compromiso permanece inquebrantable! Y el pasado <strong>encuentro virtual de voluntariado<\/strong>\u00a0se convirti\u00f3 en la ocasi\u00f3n perfecta para dedicar unas palabras de \u00e1nimo a quienes nacieron con un coraz\u00f3n especial y a sus familias.<\/p>\n<\/p>\n<p>\u00abFue un encuentro muy deseado\u00bb reconoce <strong>Mar\u00eda Alonso<\/strong>, coordinadora del programa. \u00abSon muchas horas las que comparten apoyando y acompa\u00f1ando a ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes con cardiopat\u00eda. Acaban cre\u00e1ndose fuertes lazos que les unen entre s\u00ed y, de una manera muy especial, a los \u00abmenudos\u00bb y las \u00abmenudas\u00bb y sus familias. Por ello, esta reuni\u00f3n virtual ha contado con <strong>mucha participaci\u00f3n y ha sido tan emotiva\u00bb.<\/strong><\/p>\n<p>\u00a1Un fuerte aplauso para nuestros voluntarios y voluntarias!<\/p>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/www.menudoscorazones.org\/2020\/nuestras-personas-voluntarias-envian-un-mensaje-para-las-familias\/\">Nuestras personas voluntarias env\u00edan un mensaje a las familias<\/a> aparece primero en <a rel=\"nofollow\" href=\"https:\/\/www.menudoscorazones.org\">Menudos Corazones<\/a>.<\/p>\n<p>Fuente: Menudos Corazones <a href=\"https:\/\/www.menudoscorazones.org\/2020\/nuestras-personas-voluntarias-envian-un-mensaje-para-las-familias\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nuestras personas voluntarias env\u00edan un mensaje a las familias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Las personas voluntarias de la Fundaci\u00f3n tambi\u00e9n han visto su importante labor\u00a0afectada por el coronavirus. A pesar de ello, \u00a1su compromiso permanece inquebrantable! Y el pasado encuentro virtual de voluntariado\u00a0se convirti\u00f3 en la ocasi\u00f3n perfecta para dedicar unas palabras de \u00e1nimo a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[113],"class_list":["post-5581","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-corazon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Las personas voluntarias de la Fundaci\u00f3n tambi\u00e9n han visto su importante labor\u00a0afectada por el coronavirus. A pesar de ello, \u00a1su compromiso permanece inquebrantable! Y el pasado encuentro virtual de voluntariado\u00a0se convirti\u00f3 en la ocasi\u00f3n perfecta para dedicar unas palabras de \u00e1nimo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-27T14:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Nuestras personas voluntarias env\u00edan un mensaje a las familias\",\"datePublished\":\"2020-04-27T14:49:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/\"},\"wordCount\":195,\"commentCount\":0,\"keywords\":[\"corazon\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/\",\"name\":\"Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2020-04-27T14:49:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/27\\\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuestras personas voluntarias env\u00edan un mensaje a las familias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Las personas voluntarias de la Fundaci\u00f3n tambi\u00e9n han visto su importante labor\u00a0afectada por el coronavirus. A pesar de ello, \u00a1su compromiso permanece inquebrantable! Y el pasado encuentro virtual de voluntariado\u00a0se convirti\u00f3 en la ocasi\u00f3n perfecta para dedicar unas palabras de \u00e1nimo a [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2020-04-27T14:49:42+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Nuestras personas voluntarias env\u00edan un mensaje a las familias","datePublished":"2020-04-27T14:49:42+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/"},"wordCount":195,"commentCount":0,"keywords":["corazon"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/","url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/","name":"Nuestras personas voluntarias env\u00edan un mensaje a las familias - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2020-04-27T14:49:42+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/27\/nuestras-personas-voluntarias-envian-un-mensaje-a-las-familias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Nuestras personas voluntarias env\u00edan un mensaje a las familias"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=5581"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5581\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=5581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=5581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=5581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}