{"id":5576,"date":"2020-04-26T12:14:03","date_gmt":"2020-04-26T12:14:03","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/"},"modified":"2020-04-26T12:14:03","modified_gmt":"2020-04-26T12:14:03","slug":"los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/","title":{"rendered":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Las nuevas altas tambi\u00e9n se registran entre los trabajadores de estos centros, uno de la residencia Souto de Leixa (Ferrol) hace caer los contagios entre empleados hasta los 54, seg\u00fan los \u00faltimos datos de Sanidade.<\/p>\n<p>De esta manera, la presencia de la pandemia en estos centros sigue remitiendo, pero a\u00fan cuenta con 146 casos activos entre usuarios y trabajadores. La mayor\u00eda de residentes enfermos se encuentran en el CAPD Redondela (36), en CAPD A Coru\u00f1a (26) y en DomusVi B\u00f3veda (13).<\/p>\n<p>Por su parte, los trabajadores contagiados tambi\u00e9n se concentran en el CAPD de Redondela (16), en DomusVi B\u00f3veda (9) y en CAPD A Coru\u00f1a (7).<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4238450\/0\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/\" target=\"_blank\" rel=\"noopener noreferrer\">Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Las nuevas altas tambi\u00e9n se registran entre los trabajadores de estos centros, uno de la residencia Souto de Leixa (Ferrol) hace caer los contagios entre empleados hasta los 54, seg\u00fan los \u00faltimos datos de Sanidade. De esta manera, la presencia de la pandemia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-5576","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Las nuevas altas tambi\u00e9n se registran entre los trabajadores de estos centros, uno de la residencia Souto de Leixa (Ferrol) hace caer los contagios entre empleados hasta los 54, seg\u00fan los \u00faltimos datos de Sanidade. De esta manera, la presencia de la pandemia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-26T12:14:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados\",\"datePublished\":\"2020-04-26T12:14:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/\"},\"wordCount\":155,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/\",\"name\":\"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2020-04-26T12:14:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/26\\\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/","og_locale":"es_ES","og_type":"article","og_title":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Las nuevas altas tambi\u00e9n se registran entre los trabajadores de estos centros, uno de la residencia Souto de Leixa (Ferrol) hace caer los contagios entre empleados hasta los 54, seg\u00fan los \u00faltimos datos de Sanidade. De esta manera, la presencia de la pandemia [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2020-04-26T12:14:03+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados","datePublished":"2020-04-26T12:14:03+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/"},"wordCount":155,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/","url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/","name":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2020-04-26T12:14:03+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/26\/los-centros-de-atencion-a-la-discapacidad-registran-siete-altas-entre-usuarios-y-una-de-empleados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Los centros de atenci\u00f3n a la discapacidad registran siete altas entre usuarios y una de empleados"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=5576"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5576\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=5576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=5576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=5576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}