{"id":5575,"date":"2020-04-25T12:51:07","date_gmt":"2020-04-25T12:51:07","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/"},"modified":"2020-04-25T12:51:07","modified_gmt":"2020-04-25T12:51:07","slug":"2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/","title":{"rendered":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer"},"content":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.186 finados, 1.562 personas han perdido la vida en su residencia o centro (24 m\u00e1s que ayer) mientras que otras 664 han fallecido en el hospital (648 el jueves).<\/p>\n<p>En el caso concreto de los 1.158 fallecidos con COVID-19 confirmado, 603 han perdido la vida en el hospital frente a 555 que lo han hecho en sus centros de residencia; mientras que de los 1.068 finados con s\u00edntomas compatibles pr\u00e1cticamente la totalidad (1.007) ha muerto en el centro de residencia frente a 61 que han perdido la vida en el hospital.<\/p>\n<p>Por su parte y seg\u00fan los datos facilitados este viernes, 24 de abril, por el Gobierno auton\u00f3mico, el mayor n\u00famero de fallecidos por COVID-19 confirmado se registra de nuevo en Valladolid, con 234 casos, diez m\u00e1s que ayer; seguida de Salamanca, con 197, cuatro m\u00e1s, y de Segovia, con 171, tres m\u00e1s.<\/p>\n<p>En el caso de Le\u00f3n alcanza los 160 finados, cinco m\u00e1s que el viernes; Burgos 125, cuatro m\u00e1s; \u00c1vila, Soria, que suman uno hasta los 95, 92, respectivamente, y Zamora y Palencia, que se mantienen en 43 y 41 casos, respectivamente.<\/p>\n<p>Respecto a los fallecimientos con s\u00edntomas compatibles con el coronavirus, la mayor parte se registra en Salamanca, que suma cinco casos nuevos hasta los 204; seguida de Segovia, que se mantiene con 202 casos; Le\u00f3n con 179, uno m\u00e1s; Valladolid 122, con dos m\u00e1s que el viernes, y Burgos, que se mantiene con 101.<\/p>\n<p>El resto de las provincias est\u00e1n por debajo del centenar de fallecidos con s\u00edntomas como Soria, con 87 (igual que los d\u00edas anteriores); \u00c1vila, que suma cuatro hasta los 80; Zamora sigue en 58 y Palencia, que se mantiene tambi\u00e9n en 35.<\/p>\n<p>Adem\u00e1s, y seg\u00fan los datos facilitados por la Consejer\u00eda de Familia, de esos 1.214 centros analizados por la Junta se han registrado fallecidos en 258 residencias (tres m\u00e1s que ayer), 65 de ellos con un solo caso y 115 centros con m\u00e1s de cinco casos (uno m\u00e1s que ayer).<\/p>\n<p>Por su parte, los datos de contagios confirmados (personas a las que se les ha practicado la prueba del COVID-19 con resultado positivo) asciende a 5.209, es decir uno m\u00e1s que ayer, de ellos 458 en \u00c1vila, 740 en Burgos, 742 en Le\u00f3n, 268 en Palencia, 676 en Salamanca, 521 en Segovia, 571 en Soria, 1.061 en Valladolid y 172 en Zamora.<\/p>\n<p>Finalmente, otras 1.001 personas permanecen aisladas con s\u00edntomas compatibles con COVID-19 (267 menos que este viernes), de ellos 102 en \u00c1vila, 93 en Burgos, 88 en Le\u00f3n, 61 en Palencia, 251 en Salamanca, 114 en Segovia, 59 en Soria, 158 en Valladolid y 75 en Zamora.<\/p>\n<p>En aislamiento preventivo pero sin s\u00edntomas hay otros 5.397 casos, 274 menos que este viernes, de ellos 307 en \u00c1vila, 755 en Burgos, 596 en Le\u00f3n, 600 en Palencia, 942 en Salamanca, 538 en Segovia, 612 en Soria, 458 en Valladolid y 589 en Zamora.<\/p>\n<p>En total y seg\u00fan los datos aportados este viernes por la Junta, desde que comenz\u00f3 el estado de alarma en el pa\u00eds han perdido la vida en la comunidad 3.395 personas \u00abpor cualquier causa\u00bb en estas residencias en las que residen 43.717 personas.<\/p>\n<p>TUTELADAS POR LA JUNTA<\/p>\n<p>Por \u00faltimo, en las 25 residencias que est\u00e1n tuteladas directamente por la Junta de Castilla y Le\u00f3n, y que acogen a 2.818 usuarios -hay 56 residentes hospitalizados, cinco m\u00e1s que el viernes-, se han registrado 94 fallecidos confirmados por COVID-19, cuatro m\u00e1s que ayer, mientras que 107 (los mismos que ayer) han perdido la vida por s\u00edntomas relacionados con el coronavirus.<\/p>\n<p>Adem\u00e1s, 484 permanecen en las residencias con positivo confirmado; 97 personas est\u00e1n aisladas con s\u00edntomas compatibles con el COVID-19, frente a 109 del jueves, y 597 se encuentran en aislamiento preventivo sin s\u00edntomas, cuatro menos que el d\u00eda anterior.<\/p>\n<p>Fuente: 20minutos <a href=\"https:\/\/www.20minutos.es\/noticia\/4237952\/0\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/\" target=\"_blank\" rel=\"noopener noreferrer\">2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.186 finados, 1.562 personas han perdido la vida en su residencia o centro (24 m\u00e1s que ayer) mientras que otras 664 han fallecido en el hospital (648 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[31],"class_list":["post-5575","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-discapacidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.186 finados, 1.562 personas han perdido la vida en su residencia o centro (24 m\u00e1s que ayer) mientras que otras 664 han fallecido en el hospital (648 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-25T12:51:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer\",\"datePublished\":\"2020-04-25T12:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/\"},\"wordCount\":656,\"commentCount\":0,\"keywords\":[\"discapacidad\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/\",\"name\":\"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2020-04-25T12:51:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/25\\\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/","og_locale":"es_ES","og_type":"article","og_title":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en 20minutos la siguiente noticia que os reproducimos de forma \u00edntegra: Seg\u00fan los nuevos datos facilitados por la Junta de Castilla y Le\u00f3n, de ese total de 2.186 finados, 1.562 personas han perdido la vida en su residencia o centro (24 m\u00e1s que ayer) mientras que otras 664 han fallecido en el hospital (648 [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2020-04-25T12:51:07+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer","datePublished":"2020-04-25T12:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/"},"wordCount":656,"commentCount":0,"keywords":["discapacidad"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/","url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/","name":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2020-04-25T12:51:07+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/25\/2-226-fallecidos-en-residencias-de-mayores-y-discapacidad-con-1-158-casos-confirmados-28-mas-que-ayer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"2.226 fallecidos en residencias de mayores y discapacidad, con 1.158 casos confirmados, 28 m\u00e1s que ayer"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=5575"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5575\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=5575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=5575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=5575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}