{"id":5566,"date":"2020-04-24T06:33:40","date_gmt":"2020-04-24T06:33:40","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/"},"modified":"2020-04-24T06:33:40","modified_gmt":"2020-04-24T06:33:40","slug":"dia-mundial-de-las-personas-sin-diagnostico-problematica-principal","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/","title":{"rendered":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal"},"content":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Este viernes 24 de abril se celebra el D\u00eda Mundial de las Personas Sin Diagn\u00f3stico. En la actualidad, la mitad de las personas con enfermedades raras ha sufrido un retraso en el diagn\u00f3stico de m\u00e1s de 4 a\u00f1os; para el 20% de ellas, esta demora se ha retrasado m\u00e1s de una d\u00e9cada. Como consecuencia m\u00e1s de un 30% no recibe ni tratamientos ni ayudas y como consecuencia se produce un agravamiento de su enfermedad, una espera que impida recibir un tratamiento efectivo, con el que s\u00f3lo cuentan el 5% de las enfermedades raras.<\/p>\n<p>A estas consecuencias se une el hecho de que al tratarse de enfermedades \u201csin nombre\u201d las familias se enfrentan a una situaci\u00f3n de desinformaci\u00f3n sobre cuidados, barreras en el acceso a ayudas t\u00e9cnicas y econ\u00f3micas, as\u00ed como necesidades no cubiertas en la cartera b\u00e1sica. Hoy, desde FEDER, nos sumamos a este d\u00eda y a todo el tejido asociativo que representa a este colectivo para dar mayor visibilidad a esta realidad que es, adem\u00e1s, una prioridad hist\u00f3rica de nuestro movimiento.<\/p>\n<p><h3>Objetivos 2027: diagn\u00f3sticos en menos de un a\u00f1o y mil nuevas terapias<\/h3>\n<p>Lograr dar respuesta a esta problem\u00e1tica a trav\u00e9s de la investigaci\u00f3n es uno de los retos principales. Alineados con el Consorcio Internacional de Investigaci\u00f3n de Enfermedades Raras (IRDiRC) se busca poner en valor la necesidad de dar respuesta a los objetivos planteados por el Consorcio para 2027 y que establecen la hoja de ruta a alcanzar de manera global. <\/p>\n<p>Objetivos que buscan aprobar mil nuevas terapias, desarrollar metodolog\u00edas que permitan evaluar el impacto de los diagn\u00f3sticos y las terapias aplicadas en los pacientes y uno espec\u00edfico sobre diagn\u00f3stico:la consecuci\u00f3n de un diagn\u00f3stico en el plazo de un a\u00f1o, si la patolog\u00eda se conoce en la literatura m\u00e9dica y, cuando no sea diagnosticable, se posibilite una ruta de acceso a diagn\u00f3stico e investigaci\u00f3n coordinada.<\/p>\n<p>Para lograrlo, lo que hagamos hoy en el impulso del conocimiento cient\u00edfico se transformar\u00e1 ma\u00f1ana en prevenci\u00f3n, diagn\u00f3stico y tratamiento. De esta forma, la diferencia entre el presente y el futuro de las enfermedades raras pasa por la investigaci\u00f3n.<\/p>\n<p>\u00daltima actualizaci\u00f3n: 24\/04\/2020.<\/p>\n<p>Fuente: FEDER <a href=\"https:\/\/enfermedades-raras.org\/index.php\/actualidad\/noticias-eventos\/2-feder\/13834-d%C3%ADa-mundial-de-las-personas-sin-diagn%C3%B3stico-problem%C3%A1tica-principal\" target=\"_blank\" rel=\"noopener noreferrer\">D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Este viernes 24 de abril se celebra el D\u00eda Mundial de las Personas Sin Diagn\u00f3stico. En la actualidad, la mitad de las personas con enfermedades raras ha sufrido un retraso en el diagn\u00f3stico de m\u00e1s de 4 a\u00f1os; para el 20% de ellas, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[36],"class_list":["post-5566","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-enfermedades-raras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Este viernes 24 de abril se celebra el D\u00eda Mundial de las Personas Sin Diagn\u00f3stico. En la actualidad, la mitad de las personas con enfermedades raras ha sufrido un retraso en el diagn\u00f3stico de m\u00e1s de 4 a\u00f1os; para el 20% de ellas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-24T06:33:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal\",\"datePublished\":\"2020-04-24T06:33:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/\"},\"wordCount\":420,\"commentCount\":0,\"keywords\":[\"enfermedades raras\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/\",\"name\":\"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2020-04-24T06:33:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2020\\\/04\\\/24\\\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Este viernes 24 de abril se celebra el D\u00eda Mundial de las Personas Sin Diagn\u00f3stico. En la actualidad, la mitad de las personas con enfermedades raras ha sufrido un retraso en el diagn\u00f3stico de m\u00e1s de 4 a\u00f1os; para el 20% de ellas, [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2020-04-24T06:33:40+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal","datePublished":"2020-04-24T06:33:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/"},"wordCount":420,"commentCount":0,"keywords":["enfermedades raras"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/","url":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/","name":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2020-04-24T06:33:40+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2020\/04\/24\/dia-mundial-de-las-personas-sin-diagnostico-problematica-principal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Mundial de las Personas Sin Diagn\u00f3stico: problem\u00e1tica principal"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=5566"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/5566\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=5566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=5566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=5566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}