{"id":3728,"date":"2018-05-17T11:20:07","date_gmt":"2018-05-17T11:20:07","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/"},"modified":"2018-05-17T11:20:07","modified_gmt":"2018-05-17T11:20:07","slug":"feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/","title":{"rendered":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter"},"content":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p><p><span style=\"font-size: 11.97px;line-height: 1.3\">El Vall d\u2019Hebron Barcelona Campus Hospitalario organiza el pr\u00f3ximo 25 de mayo la Jornada sobre el S\u00edndrome de Klinefelter. FEDER estar\u00e1 presente en esta Jornada gracias a la asistencia de nuestro miembro de Junta Directiva, Jordi Cruz.<\/span><\/p>\n<p>Esta Jornada pretende ser una jornada informativa y distendida en la que tambi\u00e9n est\u00e1 prevista la colaboraci\u00f3n y participaci\u00f3n activa de representantes de las asociaciones de pacientes. Durante la Jornada se tratar\u00e1n temas de inter\u00e9s como: Orientaci\u00f3n e informaci\u00f3n (qu\u00e9 es y c\u00f3mo comunicar al paciente y su familia), Aspectos endocrinol\u00f3gicos del ni\u00f1o y del adulto, Aspectos asesoramiento gen\u00e9tico y reproductivo, Aspectos psicol\u00f3gicos en este \u00faltimo tema se contar\u00e1 con la participaci\u00f3n de los pacientes y familias.<\/p>\n<p>Esta Jornada est\u00e1 dirigida pacientes y familias con s\u00edndrome de Klinefelter organizada por un equipo multidisciplinar de especialistas del Hospital Vall d&#8217;Hebron de Barcelona implicados en el diagn\u00f3stico y seguimiento de estos pacientes y cuenta con la colaboraci\u00f3n de la Asociaci\u00f3n Catalana de S\u00edndrome de Klinefelter.<\/p>\n<p>La jornada se realizar\u00e1 en el M\u00f3dulo de Gen\u00e9tica Cl\u00ednica y Enfermedades Minoritarias del Hospital Vall d\u2019Hebr\u00f3n a partir de las 4:00 h.<\/p>\n<p style=\"text-align: right\">\u00daltima actualizaci\u00f3n: 17 de mayo de 2018.<\/p>\n<\/p>\n<p>Fuente: FEDER <a href=\"https:\/\/enfermedades-raras.org\/index.php\/actualidad\/noticias-eventos\/2-feder\/10600-feder-presente-en-la-jornada-sobre-s%C3%ADndrome-de-klinefelter\" target=\"_blank\">FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: El Vall d\u2019Hebron Barcelona Campus Hospitalario organiza el pr\u00f3ximo 25 de mayo la Jornada sobre el S\u00edndrome de Klinefelter. FEDER estar\u00e1 presente en esta Jornada gracias a la asistencia de nuestro miembro de Junta Directiva, Jordi Cruz. Esta Jornada pretende ser una jornada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[36],"class_list":["post-3728","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-enfermedades-raras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: El Vall d\u2019Hebron Barcelona Campus Hospitalario organiza el pr\u00f3ximo 25 de mayo la Jornada sobre el S\u00edndrome de Klinefelter. FEDER estar\u00e1 presente en esta Jornada gracias a la asistencia de nuestro miembro de Junta Directiva, Jordi Cruz. Esta Jornada pretende ser una jornada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-17T11:20:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter\",\"datePublished\":\"2018-05-17T11:20:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/\"},\"wordCount\":247,\"commentCount\":0,\"keywords\":[\"enfermedades raras\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/\",\"name\":\"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2018-05-17T11:20:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/17\\\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/","og_locale":"es_ES","og_type":"article","og_title":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: El Vall d\u2019Hebron Barcelona Campus Hospitalario organiza el pr\u00f3ximo 25 de mayo la Jornada sobre el S\u00edndrome de Klinefelter. FEDER estar\u00e1 presente en esta Jornada gracias a la asistencia de nuestro miembro de Junta Directiva, Jordi Cruz. Esta Jornada pretende ser una jornada [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2018-05-17T11:20:07+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter","datePublished":"2018-05-17T11:20:07+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/"},"wordCount":247,"commentCount":0,"keywords":["enfermedades raras"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/","url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/","name":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2018-05-17T11:20:07+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/17\/feder-presente-en-la-jornada-sobre-sindrome-de-klinefelter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"FEDER presente en la Jornada sobre S\u00edndrome de Klinefelter"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3728\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=3728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}