{"id":3708,"date":"2018-05-11T12:25:40","date_gmt":"2018-05-11T12:25:40","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/"},"modified":"2018-05-11T12:25:40","modified_gmt":"2018-05-11T12:25:40","slug":"besos-con-corazon-para-los-ninos-hospitalizados","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/","title":{"rendered":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados"},"content":{"rendered":"<p>Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Celebramos el D\u00eda del Ni\u00f1o Hospitalizado, rindiendo homenaje a los peques ingresados.<\/p>\n<p>Fuente: Menudos Corazones <a href=\"https:\/\/www.menudoscorazones.org\/actualidad\/besos-con-corazon-para-los-ninos-hospitalizados\/\" target=\"_blank\">Besos con coraz\u00f3n para los ni\u00f1os hospitalizados<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Celebramos el D\u00eda del Ni\u00f1o Hospitalizado, rindiendo homenaje a los peques ingresados. Fuente: Menudos Corazones Besos con coraz\u00f3n para los ni\u00f1os hospitalizados<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[113],"class_list":["post-3708","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-corazon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Celebramos el D\u00eda del Ni\u00f1o Hospitalizado, rindiendo homenaje a los peques ingresados. Fuente: Menudos Corazones Besos con coraz\u00f3n para los ni\u00f1os hospitalizados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-11T12:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados\",\"datePublished\":\"2018-05-11T12:25:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/\"},\"wordCount\":48,\"commentCount\":0,\"keywords\":[\"corazon\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/\",\"name\":\"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2018-05-11T12:25:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/besos-con-corazon-para-los-ninos-hospitalizados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/","og_locale":"es_ES","og_type":"article","og_title":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en Menudos Corazones la siguiente noticia que os reproducimos de forma \u00edntegra: Celebramos el D\u00eda del Ni\u00f1o Hospitalizado, rindiendo homenaje a los peques ingresados. Fuente: Menudos Corazones Besos con coraz\u00f3n para los ni\u00f1os hospitalizados","og_url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2018-05-11T12:25:40+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados","datePublished":"2018-05-11T12:25:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/"},"wordCount":48,"commentCount":0,"keywords":["corazon"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/","url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/","name":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2018-05-11T12:25:40+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/besos-con-corazon-para-los-ninos-hospitalizados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Besos con coraz\u00f3n para los ni\u00f1os hospitalizados"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=3708"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3708\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=3708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=3708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=3708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}