{"id":3706,"date":"2018-05-11T05:53:00","date_gmt":"2018-05-11T05:53:00","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/"},"modified":"2018-05-11T05:53:00","modified_gmt":"2018-05-11T05:53:00","slug":"mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/","title":{"rendered":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social"},"content":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<p>Hemos abierto el plazo de inscripci\u00f3n para su curso online \u2018Formaci\u00f3n en habilidades para la gesti\u00f3n eficiente de asociaciones de pacientes con enfermedades raras\u2019; un ciclo que alcanza incluye m\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social.<\/p>\n<p>A trav\u00e9s de esta iniciativa, en la que las asociaciones se pueden matricular antes del 24 de mayo, buscamos construir un movimiento asociativo l\u00edder en su campo, con habilidades para gestionar y mejorar su trabajo.&nbsp;<\/p>\n<p>Hasta la fecha, ha formado a m\u00e1s de 355 alumnos de m\u00e1s de 270 entidades, lo que supone casi el 80% de las entidades que conforman actualmente la Federaci\u00f3n, que suman un total de 339.<\/p>\n<p>Todo ello a trav\u00e9s de un pr\u00e1ctico curso, con las posibilidades y ventajas de acceder a trav\u00e9s de una plataforma virtual: facilidad de acceso (en cualquier lugar y momento), mayor flexibilidad horaria (24 horas 7 d\u00edas a la semana), auto-organizaci\u00f3n en el propio ritmo de estudio, compatibilidad con otras actividades y responsabilidades (con el trabajo y\/o con las tareas de cuidado), etc.<\/p>\n<h3>Un total de 11 m\u00f3dulos para el liderazgo<\/h3>\n<p>Aspectos como la comunicaci\u00f3n, la eficacia, la gesti\u00f3n de equipos y conflictos, el liderazgo, la negociaci\u00f3n, la motivaci\u00f3n o el marketing son algunos de los pilares que conforman los once m\u00f3dulos tem\u00e1ticos del ciclo.<\/p>\n<p>De ah\u00ed que FEDER haya priorizado la participaci\u00f3n de miembros de las Juntas Directivas de las entidades, aquellas asociaciones de reciente creaci\u00f3n o aquellas organizaciones que no hayan podido participar en las ediciones previas.<\/p>\n<p>Caf\u00e9s debate, ideas fuerza, presentaciones, casos pr\u00e1cticos, cuestionarios y art\u00edculos son algunas de las herramientas con las que trabajar\u00e1n los alumnos, adquiriendo, adem\u00e1s, un certificado acreditativo al finalizar el curso.<\/p>\n<p style=\"text-align: right\">\u00daltima actualizaci\u00f3n: 10\/05\/2018.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: FEDER <a href=\"https:\/\/enfermedades-raras.org\/index.php\/actualidad\/noticias-eventos\/2-feder\/10556-m%C3%A1s-100-horas%2C-m%C3%A1s-de-60-plazas-y-un-objetivo-liderar-la-transformaci%C3%B3n-social\" target=\"_blank\">M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Hemos abierto el plazo de inscripci\u00f3n para su curso online \u2018Formaci\u00f3n en habilidades para la gesti\u00f3n eficiente de asociaciones de pacientes con enfermedades raras\u2019; un ciclo que alcanza incluye m\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[36],"class_list":["post-3706","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-enfermedades-raras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Hemos abierto el plazo de inscripci\u00f3n para su curso online \u2018Formaci\u00f3n en habilidades para la gesti\u00f3n eficiente de asociaciones de pacientes con enfermedades raras\u2019; un ciclo que alcanza incluye m\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-11T05:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social\",\"datePublished\":\"2018-05-11T05:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/\"},\"wordCount\":351,\"commentCount\":0,\"keywords\":[\"enfermedades raras\"],\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/\",\"name\":\"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2018-05-11T05:53:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2018\\\/05\\\/11\\\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Leemos en FEDER la siguiente noticia que os reproducimos de forma \u00edntegra: Hemos abierto el plazo de inscripci\u00f3n para su curso online \u2018Formaci\u00f3n en habilidades para la gesti\u00f3n eficiente de asociaciones de pacientes con enfermedades raras\u2019; un ciclo que alcanza incluye m\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social. [&hellip;]","og_url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2018-05-11T05:53:00+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social","datePublished":"2018-05-11T05:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/"},"wordCount":351,"commentCount":0,"keywords":["enfermedades raras"],"articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/","url":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/","name":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2018-05-11T05:53:00+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2018\/05\/11\/mas-100-horas-mas-de-60-plazas-y-un-objetivo-liderar-la-transformacion-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s 100 horas, m\u00e1s de 60 plazas y un objetivo: liderar la transformaci\u00f3n social"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=3706"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/3706\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=3706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=3706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=3706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}