{"id":10773,"date":"2025-01-28T06:46:03","date_gmt":"2025-01-28T06:46:03","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/"},"modified":"2025-01-28T06:46:03","modified_gmt":"2025-01-28T06:46:03","slug":"aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/","title":{"rendered":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>Los trabajadores aut\u00f3nomos con <a href=\"https:\/\/www.20minutos.es\/minuteca\/discapacidad\/\" title=\"Discapacidad\" target=\"_blank\">discapacidad<\/a> igual o superior el 33 por ciento han aumentado un 2,5 por ciento en el a\u00f1o 2024, llegando a los <b>25.811 en total<\/b>, seg\u00fan datos aportados por la Tesorer\u00eda General de la Seguridad Social al Comit\u00e9 Espa\u00f1ol de Representantes de Personas con Discapacidad (<a href=\"https:\/\/www.20minutos.es\/minuteca\/cermi\/\" title=\"Cermi\" target=\"_blank\">CERMI<\/a>).<\/p>\n<p>El incremento en ese a\u00f1o 2024 <b>fue de 641 trabajadores aut\u00f3nomos con discapacidad<\/b>. Este aumento producido en el a\u00f1o 2024 fue algo superior al experimentado en el a\u00f1o 2023, en el que el crecimiento fue de un 2,2 por ciento, en concreto, 564 trabajadores m\u00e1s.<\/p>\n<p>De este total de 25.811 trabajadores aut\u00f3nomos con discapacidad alcanzado a fecha de 31 de diciembre de 2024, <b>9.592 eran mujeres y 16.219 varones<\/b>, por lo que la diferencia por sexo es muy acusada en detrimento de las mujeres con discapacidad.<\/p>\n<p>A juicio del <a href=\"https:\/\/www.20minutos.es\/minuteca\/cermi\/\" title=\"Cermi\" target=\"_blank\">CERMI<\/a>, ese incremento de 2,5 puntos en 2024, indica que el emprendimiento, a pesar de sus<b> t\u00e9rminos globalmente modestos<\/b>, sigue siendo una v\u00eda de inclusi\u00f3n laboral atractiva para las personas con discapacidad que \u00abcada a\u00f1o escala posiciones en su aportaci\u00f3n a la creaci\u00f3n general de empleo para este grupo de poblaci\u00f3n\u00bb.<\/p>\n<p>Esta tendencia positiva, necesita de una acci\u00f3n p\u00fablica \u00abm\u00e1s intensa\u00bb por lo que el CERMI reclama al Gobierno un<b> robustecimiento de los incentivos y bonificaciones a los aut\u00f3nomos con discapacidad<\/b>, \u00abhaci\u00e9ndolos m\u00e1s reforzado para las mujeres, que ampl\u00ede este camino de acceso al empleo y permita crecimientos mucho m\u00e1s elevados en los a\u00f1os pr\u00f3ximos\u00bb.<\/p>\n<p>A su juicio, entre estas medidas debe estar necesariamente la <b>recuperaci\u00f3n de las reducciones de Seguridad Social<\/b> \u00abpara los trabajadores que adquieren la discapacidad siendo ya aut\u00f3nomos, que ahora mismo est\u00e1s desprotegidos\u00bb.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5676696\/0\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del total de aut\u00f3nomos con discapacidad a finales de 2024, 9.592 eran mujeres y 16.219 varones.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-10773","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Del total de aut\u00f3nomos con discapacidad a finales de 2024, 9.592 eran mujeres y 16.219 varones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T06:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811\",\"datePublished\":\"2025-01-28T06:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/\"},\"wordCount\":327,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/\",\"name\":\"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2025-01-28T06:46:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2025\\\/01\\\/28\\\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/","og_locale":"es_ES","og_type":"article","og_title":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Del total de aut\u00f3nomos con discapacidad a finales de 2024, 9.592 eran mujeres y 16.219 varones.","og_url":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2025-01-28T06:46:03+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811","datePublished":"2025-01-28T06:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/"},"wordCount":327,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/","url":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/","name":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811 - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2025-01-28T06:46:03+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2025\/01\/28\/aumenta-un-2-5-por-ciento-numero-trabajadores-autonomos-con-discapacidad-ano-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"En 2024 aument\u00f3 un 2,5% el n\u00famero de aut\u00f3nomos con discapacidad en Espa\u00f1a, ya son 25.811"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=10773"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10773\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=10773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=10773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=10773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}