{"id":10437,"date":"2024-10-11T05:43:23","date_gmt":"2024-10-11T05:43:23","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/"},"modified":"2024-10-11T05:43:23","modified_gmt":"2024-10-11T05:43:23","slug":"ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/","title":{"rendered":"La &#8216;ley ELA&#8217; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \u00abEs una enfermedad muy cara\u00bb"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>La \u2018<b>ley ELA<\/b>\u2019 costar\u00e1 entre 184 y 230 millones de euros anuales, seg\u00fan un estudio de la Fundaci\u00f3n Luz\u00f3n publicado este jueves, el mismo d\u00eda que el <a href=\"https:\/\/www.20minutos.es\/minuteca\/congreso-de-los-diputados\/\" title=\"Congreso de los Diputados\" target=\"_blank\" rel=\"noopener\">Congreso de los Diputados<\/a> aprob\u00f3 esta normativa, aunque debe seguir su tramitaci\u00f3n en el Senado, que \u00abcubrir\u00e1, a partir de ahora, los altos costes que deben asumir los m\u00e1s de 4.000 pacientes con <a href=\"https:\/\/www.20minutos.es\/minuteca\/ela-esclerosis-lateral-amiotrofica\/\" title=\"ELA - Esclerosis lateral amiotr\u00f3fica\" target=\"_blank\" rel=\"noopener\">Esclerosis Lateral Amiotr\u00f3fica (ELA)<\/a> en Espa\u00f1a.<\/p>\n<p>Seg\u00fan inform\u00f3 la Fundaci\u00f3n Luz\u00f3n, la ELA \u00abes una enfermedad muy cara\u00bb, sobre todo, en su fase m\u00e1s avanzada. As\u00ed se desprende del <b>\u2018Estudio de Costes de la ELA para las familias en Espa\u00f1a\u2019 <\/b>elaborado por esta organizaci\u00f3n y que cuantifica los gastos que deben asumir los pacientes de ELA a lo largo de su enfermedad.<\/p>\n<p>Este informe cifra el coste que deber\u00e1 asumir el Estado una vez salga adelante. La partida presupuestaria para sufragar solamente los <b>costes directos que actualmente asumen las familias <\/b>de los enfermos de ELA deber\u00e1 oscilar entre los 184 y 230 millones de euros.<\/p>\n<p>Desde la Fundaci\u00f3n Luz\u00f3n se\u00f1alaron que son datos estimativos, ya que actualmente<b> no se conoce el n\u00famero exacto de afectados de ELA en Espa\u00f1a <\/b>y, por tanto, \u00abno se puede calcular con total precisi\u00f3n cu\u00e1nto le costar\u00e1 al Estado sufragar los costes fijos y recurrentes de estos enfermos\u00bb.<\/p>\n<p>Sin embargo, gracias a los datos aportados por las asociaciones de pacientes y hospitales de toda Espa\u00f1a, los datos de este informe son una <b>aproximaci\u00f3n muy cercana a la realidad de la ELA<\/b>.<\/p>\n<h2>Registro ELA<\/h2>\n<p>Para que estos datos sean lo m\u00e1s precisos posibles de cara a los pr\u00f3ximos a\u00f1os, la entidad que fund\u00f3 Francisco Luz\u00f3n puso en marcha el Registro Nacional de Pacientes de ELA junto al <b>Instituto de Salud Carlos II<\/b>I.<\/p>\n<p>Los datos cl\u00ednicos, socioecon\u00f3micos y geogr\u00e1ficos de este registro permitir\u00e1n fomentar la investigaci\u00f3n b\u00e1sica y cl\u00ednica, favorecer la toma de decisiones para una adecuada planificaci\u00f3n sanitaria, y una <b>correcta distribuci\u00f3n de recursos sociales<\/b>, sanitarios y de investigaci\u00f3n.<\/p>\n<p>Actualmente, seg\u00fan este estudio, una persona con ELA en la fase m\u00e1s avanzada de la enfermedad, en la que requiere cuidados en todas sus actividades cotidianas, debe asumir <b>unos costes anuales de m\u00e1s de 114.000 euros<\/b>. Sin embargo, la cifra ser\u00e1 menor si el paciente se encuentra en la<b> fase inicial (37.000 euros anuales)<\/b>, pero se incrementa de forma significativa cuando se encuentra en la fase intermedia, donde puede llegar a pagar <b>hasta 95.000 euros al a\u00f1o<\/b> entre gastos fijos y recurrentes.<\/p>\n<p>La Ley ELA incorpora otras medidas que no est\u00e1n cuantificadas en este documento y que precisar\u00e1n tambi\u00e9n de una financiaci\u00f3n espec\u00edfica, ya que en el informe de la Fundaci\u00f3n Luz\u00f3n<b> solo se cuantifica cu\u00e1nto le costar\u00e1 al Estado sufragar los gastos fijos y recurrentes<\/b> que hasta ahora asum\u00edan los enfermos de ELA y sus familias.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5642782\/0\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan un estudio de la Fundaci\u00f3n Luz\u00f3n, una persona con ELA en la fase m\u00e1s avanzada supone un coste de unos 114.000 euros al a\u00f1o.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-10437","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La &#039;ley ELA&#039; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: &quot;Es una enfermedad muy cara&quot; - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La &#039;ley ELA&#039; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: &quot;Es una enfermedad muy cara&quot; - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan un estudio de la Fundaci\u00f3n Luz\u00f3n, una persona con ELA en la fase m\u00e1s avanzada supone un coste de unos 114.000 euros al a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T05:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"La &#8216;ley ELA&#8217; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \u00abEs una enfermedad muy cara\u00bb\",\"datePublished\":\"2024-10-11T05:43:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/\"},\"wordCount\":548,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/\",\"name\":\"La 'ley ELA' costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \\\"Es una enfermedad muy cara\\\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2024-10-11T05:43:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/10\\\/11\\\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La &#8216;ley ELA&#8217; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: &#8220;Es una enfermedad muy cara&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La 'ley ELA' costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \"Es una enfermedad muy cara\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/","og_locale":"es_ES","og_type":"article","og_title":"La 'ley ELA' costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \"Es una enfermedad muy cara\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Seg\u00fan un estudio de la Fundaci\u00f3n Luz\u00f3n, una persona con ELA en la fase m\u00e1s avanzada supone un coste de unos 114.000 euros al a\u00f1o.","og_url":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2024-10-11T05:43:23+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"La &#8216;ley ELA&#8217; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \u00abEs una enfermedad muy cara\u00bb","datePublished":"2024-10-11T05:43:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/"},"wordCount":548,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/","url":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/","name":"La 'ley ELA' costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: \"Es una enfermedad muy cara\" - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2024-10-11T05:43:23+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/10\/11\/ley-ela-costara-entre-184-230-millones-euros-ano-segun-un-estudio-fundacion-luzon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"La &#8216;ley ELA&#8217; costar\u00e1 entre 184 y 230 millones de euros al a\u00f1o, seg\u00fan la Fundaci\u00f3n Luz\u00f3n: &#8220;Es una enfermedad muy cara&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=10437"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10437\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=10437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=10437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=10437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}