{"id":10129,"date":"2024-06-24T15:52:05","date_gmt":"2024-06-24T15:52:05","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/"},"modified":"2024-06-24T15:52:05","modified_gmt":"2024-06-24T15:52:05","slug":"junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/","title":{"rendered":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>Fomentar la inclusi\u00f3n laboral de las personas con discapacidad y reducir la desigualdad entre hombres y mujeres en este \u00e1mbito. Son los principales objetivos del II Plan de Empleo de Personas con Discapacidad que la Junta va a poner en marcha entre 2024 y 2028 y que podr\u00e1 <b>beneficiar a m\u00e1s de 161.000 personas con diversidad funcional que pueden trabajar<\/b>, toda vez que la cifra actualmente no llega ni a la mitad.<\/p>\n<p>Para poner en marcha esta nueva estrategia, la Consejer\u00eda de Empleo, Empresa y Trabajo Aut\u00f3nomo ha desarrollado un estudio de diagn\u00f3stico que revela que de las 380.700 personas con discapacidad que hay en Andaluc\u00eda, m\u00e1s de 161.000 est\u00e1n en edad de trabajar y pueden hacerlo. <b>Sin embargo, solo tienen empleo 76.700, es decir, menos del 48%<\/b>. Otras 36.300 est\u00e1n desempleadas y 13.000 est\u00e1n estudiando.<\/p>\n<p>El informe, que este lunes ha presentado la viceconsejera del ramo, Beatriz Barranco, a diversas entidades en unas jornadas participativas en Sevilla, pone de manifiesto tambi\u00e9n que solo el 20,15% de las personas con discapacidad est\u00e1n ocupadas, frente al 60,23% de la poblaci\u00f3n general; y que <b>la tasa de paro en este colectivo (32,15%) es 13 puntos superior a la general<\/b>.<\/p>\n<p>De hecho, y seg\u00fan los \u00faltimos datos del Observatorio Argos, del Servicio Andaluz de Empleo (SAE), consultados por este medio, el pasado mayo de este a\u00f1o se registraron en la comunidad 264.042 contratos y <b>solo 4.360 a personas con discapacidad<\/b>, de los que el 71,5% fueron temporales.<\/p>\n<p>Por otro lado, la Consejer\u00eda ha detectado que la mayor parte de los incentivos al empleo para las personas con discapacidad est\u00e1n dirigidos al llamado empleo protegido en los Centros Especiales de Empleo (aquellos cuya plantilla est\u00e1 formada por, al menos, un 70% de personas con discapacidad), con m\u00e1s de 88 millones de euros el a\u00f1o pasado; frente a los <b>214.000 euros que se invirtieron en ayudas al acceso de estas personas a empresas ordinarias<\/b>. M\u00e1s satisfactorios, destac\u00f3 la <a href=\"https:\/\/www.20minutos.es\/minuteca\/junta-de-andalucia\/\" title=\"Junta de Andaluc\u00eda\">Junta<\/a>, son los datos relativos al empleo p\u00fablico, que en Andaluc\u00eda alcanza el 21% en relaci\u00f3n con el peso poblacional de este colectivo, lo que \u00abmuestra la eficacia de los cupos de reserva y cuota\u00bb, mientras que el autoempleo solo alcanza al 8,8%.<\/p>\n<p>Con todos estos datos sobre la mesa, el informe preliminar de la Consejer\u00eda dirigida por Roc\u00edo Blanco apunta a que los principales problemas a los que se enfrentan los andaluces con diversidad funcional son la falta de informaci\u00f3n sobre sus capacidades y la falta de formaci\u00f3n reglada y adaptada seg\u00fan los distintos perfiles y contenidos. Adem\u00e1s de las <b>barreras que presenta la digitalizaci\u00f3n en los procesos de b\u00fasqueda de trabajo<\/b>. En este sentido, los retos identificados pasan por favorecer una mayor participaci\u00f3n de las personas con diversidad funcional en el mercado laboral, con empleos de calidad, y disminuir las desigualdades tambi\u00e9n en este \u00e1mbito detectadas entre hombres y mujeres; as\u00ed como impulsar medidas encaminadas a la formaci\u00f3n para el empleo, la formaci\u00f3n profesional, la orientaci\u00f3n, la intermediaci\u00f3n y el acompa\u00f1amiento en la inserci\u00f3n.<\/p>\n<p>\u00abLa inclusi\u00f3n de las personas con discapacidad en el mercado laboral no es solo una cuesti\u00f3n de justicia social, sino una oportunidad para enriquecer nuestra econom\u00eda y fortalecer nuestro tejidos social\u00bb, ha destacado la viceconsejera, que detalla que este II Plan de Empleo se elaborar\u00e1 en base a un proceso \u00abparticipativo\u00bb que implica la colaboraci\u00f3n de \u00abdiversos actores\u00bb, ya que esto \u00abno puede ser un esfuerzo asilado desde la Administraci\u00f3n p\u00fablica\u00bb.<\/p>\n<p>La Junta tambi\u00e9n ha subrayado que durante el a\u00f1o 2022 hubo cerca de <b>19.000 personas con discapacidad que se beneficiaron en la comunidad de las medidas de apoyo a la creaci\u00f3n de empleo del SAE<\/b>; otras 14.319 participaron en un itinerario personalizado de inserci\u00f3n a trav\u00e9s de Andaluc\u00eda Orienta; y 10.741 m\u00e1s fueron derivadas al programa de acompa\u00f1amiento.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5524217\/0\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Menos de la mitad de la poblaci\u00f3n con diversidad funcional en la comunidad que puede trabajar tiene un empleo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-10129","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Menos de la mitad de la poblaci\u00f3n con diversidad funcional en la comunidad que puede trabajar tiene un empleo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T15:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda\",\"datePublished\":\"2024-06-24T15:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/\"},\"wordCount\":697,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/\",\"name\":\"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2024-06-24T15:52:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/24\\\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/","og_locale":"es_ES","og_type":"article","og_title":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Menos de la mitad de la poblaci\u00f3n con diversidad funcional en la comunidad que puede trabajar tiene un empleo.","og_url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2024-06-24T15:52:05+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda","datePublished":"2024-06-24T15:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/"},"wordCount":697,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/","url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/","name":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2024-06-24T15:52:05+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/24\/junta-impulsa-un-plan-empleo-que-beneficiara-mas-161-000-personas-con-discapacidad-andalucia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"La Junta impulsa un plan de empleo que beneficiar\u00e1 a m\u00e1s de 161.000 personas con discapacidad en Andaluc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=10129"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10129\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=10129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=10129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=10129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}