{"id":10120,"date":"2024-06-20T11:35:22","date_gmt":"2024-06-20T11:35:22","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/"},"modified":"2024-06-20T11:35:22","modified_gmt":"2024-06-20T11:35:22","slug":"educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/","title":{"rendered":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>Gema Canales, una joven con tetraparesia esp\u00e1stica dist\u00f3nica y sin capacidad de lenguaje oral de Ol\u00edas del Rey (Toledo), <b>ha marcado un hito<\/b> al superar la <a href=\"https:\/\/www.20minutos.es\/minuteca\/eso\/\" title=\"ESO\">Educaci\u00f3n Secundaria Obligatoria (ESO)<\/a> gracias a la ayuda de tecnolog\u00edas de apoyo.<\/p>\n<p>Seg\u00fan ha informado la &#8216;Fundaci\u00f3n Gema Canales&#8217;, la joven estudiante utiliza un dispositivo de comunicaci\u00f3n que <b>sigue el movimiento de sus ojos y emite una voz sintetizada<\/b> de lo que escribe, con el que ha podido realizar ex\u00e1menes, presentar trabajos y participar activamente en clase.<\/p>\n<p>Este dispositivo<b> ha sido el aliado de Gema desde Primero de Educaci\u00f3n Primaria <\/b>y el que le ha permitido superar las barreras educativas con los apoyos adecuados. El caso de Gema \u00abno solo es un triunfo personal, sino <b>un ejemplo inspirador<\/b> ya que su \u00e9xito pone de manifiesto la importancia de la tecnolog\u00eda para abrir nuevas posibilidades para otras personas con discapacidad\u00bb, ha resaltado la fundaci\u00f3n.<\/p>\n<p>Su historia <b>ha inspirado la creaci\u00f3n de la &#8216;Fundaci\u00f3n Gema Canales&#8217;,<\/b> cuyo fin es mejorar la calidad de vida de las personas con <a href=\"https:\/\/www.20minutos.es\/minuteca\/paralisis-cerebral\/\" title=\"Par\u00e1lisis cerebral\">par\u00e1lisis cerebral<\/a> y sus familias, a trav\u00e9s de apoyo emocional, servicios de atenci\u00f3n temprana y terapias que ayudan a estas personas a alcanzar su m\u00e1ximo potencial. <\/p>\n<p>En la Fundaci\u00f3n Gema Canales defienden \u00ab<b>la necesidad de adquirir dispositivos de comunicaci\u00f3n<\/b>, con una estrategia de entrega rotatoria, dotando a los usuarios y sus familias de tecnolog\u00eda, formaci\u00f3n y asesoramiento que les ayuden a conseguir sus objetivos\u00bb.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5522951\/0\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gema Canales, una joven con tetraparesia esp\u00e1stica dist\u00f3nica y sin capacidad de lenguaje oral de Ol\u00edas del Rey (Toledo), ha marcado un hito al superar la Educaci\u00f3n Secundaria Obligatoria (ESO) gracias a la ayuda de tecnolog\u00edas de apoyo.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-10120","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Gema Canales, una joven con tetraparesia esp\u00e1stica dist\u00f3nica y sin capacidad de lenguaje oral de Ol\u00edas del Rey (Toledo), ha marcado un hito al superar la Educaci\u00f3n Secundaria Obligatoria (ESO) gracias a la ayuda de tecnolog\u00edas de apoyo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T11:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada\",\"datePublished\":\"2024-06-20T11:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/\"},\"wordCount\":298,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/\",\"name\":\"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2024-06-20T11:35:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/20\\\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/","og_locale":"es_ES","og_type":"article","og_title":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Gema Canales, una joven con tetraparesia esp\u00e1stica dist\u00f3nica y sin capacidad de lenguaje oral de Ol\u00edas del Rey (Toledo), ha marcado un hito al superar la Educaci\u00f3n Secundaria Obligatoria (ESO) gracias a la ayuda de tecnolog\u00edas de apoyo.","og_url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2024-06-20T11:35:22+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada","datePublished":"2024-06-20T11:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/"},"wordCount":298,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/","url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/","name":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2024-06-20T11:35:22+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/20\/educacion-inclusiva-gema-canales-primera-joven-con-tetraparesia-sin-lenguaje-oral-que-supera-eso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"Gema Canales, con tetraparesia y sin lenguaje oral, logra superar la ESO gracias a un dispositivo que sigue su mirada"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=10120"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10120\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=10120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=10120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=10120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}