{"id":10109,"date":"2024-06-17T05:57:02","date_gmt":"2024-06-17T05:57:02","guid":{"rendered":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/"},"modified":"2024-06-17T05:57:02","modified_gmt":"2024-06-17T05:57:02","slug":"maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores","status":"publish","type":"post","link":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/","title":{"rendered":"La Fiscal\u00eda pide ayuda para que no haya \u00abvoluntades cautivas\u00bb entre las personas mayores que est\u00e9n a cargo de cuidadores"},"content":{"rendered":"<p>Leemos en Discapacidad la siguiente noticia que os reproducimos de forma \u00edntegra: <\/p>\n<div>\n<p>La fiscal de sala del Tribunal Supremo y coordinadora de los servicios de atenci\u00f3n a las personas con discapacidad y a los mayores, <b>Mar\u00eda Jos\u00e9 Segarra<\/b>, ha explicado que nota <b>\u00abvoluntades cautivas<\/b>\u00bb entre las personas mayores que est\u00e1n al cargo de cuidadores, por lo que ha apelado a que sus problemas lleguen a la Fiscal\u00eda.<\/p>\n<p>Con motivo del <b>D\u00eda Mundial de Toma de Conciencia del Abuso y Maltrato en la Vejez<\/b>, Segarra explica en una entrevista con EFE que la ausencia de denuncia es una cuesti\u00f3n clave para abordar estos casos, para lo que la Fiscal\u00eda ya ha adoptado medidas como el convenio que tiene con Cruz Roja.<\/p>\n<p>Las personas afectadas est\u00e1n en situaci\u00f3n de \u00ab<b>extrema vulnerabilidad<\/b>\u00bb porque viven al cuidado de terceros y temen perder su favor o que las ingresen en residencias, por lo que ve incluso \u00abvoluntades cautivas\u00bb.<\/p>\n<p>\u00abQueremos que esa cifra de ausencia de denuncia o simplemente de <b>transmitir que no estoy de acuerdo con lo que est\u00e1n decidiendo por m\u00ed<\/b>, nos llegue\u00bb, contin\u00faa.<\/p>\n<p>Es una cuesti\u00f3n clave para la Fiscal\u00eda, que ve como l\u00ednea de trabajo ese contacto \u00abcon el tercer sector\u00bb que, en el caso de Cruz Roja, se traduce en que hay una puesta en conocimiento directa sin necesidad de denuncia.<\/p>\n<p>\u00abLos fiscales que llevamos <a href=\"https:\/\/www.20minutos.es\/minuteca\/discapacidad\/\" title=\"Discapacidad\" target=\"_blank\" rel=\"noopener\">discapacidad<\/a> en el \u00e1mbito civil hacemos un estudio para ver qu\u00e9 es lo que pasa en esa familia, qu\u00e9 es lo que quiere la persona. Hablamos con ella o a trav\u00e9s de trabajadores sociales que tenemos en las fiscal\u00edas o en los ayuntamientos y si es necesaria alguna actuaci\u00f3n, que puede ser solo en el orden civil, para prestar el apoyo a las personas, o pueden ir en el orden penal, a interponer una denuncia si lo que hay es una situaci\u00f3n delictiva\u00bb, a\u00f1ade.<\/p>\n<p>Pero los problemas de las personas mayores no solo son de<b> maltrato directo<\/b> sino que se extienden a otras cuestiones como las<b> estafas o las apropiaciones patrimoniales<\/b>, para las que la Fiscal\u00eda tambi\u00e9n ha suscrito un convenio con las entidades bancarias por si se producen movimientos de dinero que pueden ir contra su voluntad.<\/p>\n<p>\u00abTiene una doble perspectiva, por un lado<b>, proteger el patrimonio de las personas mayores <\/b>cuando tenemos una mayor vulnerabilidad, incluso ante los medios tecnol\u00f3gicos. Pero adem\u00e1s, en ese protocolo con los bancos hemos querido darle a la persona y facilitar a su familia c\u00f3mo desarrollar su vida al margen de incapacitarla\u00bb, relata.<\/p>\n<h1>Es necesario el cambio de interpretaci\u00f3n de \u00ablas antiguas tutelas, las antiguas patrias potestades prorrogadas\u00bb que deben interpretarse de acuerdo a la nueva ley<\/h1>\n<p>En concreto, se ha creado un acuerdo interpretativo de las nuevas formas de apoyo de la ley 8\/1 por la que se reforma la legislaci\u00f3n civil y procesal para el <b>apoyo a las personas con discapacidad<\/b> en el ejercicio de su capacidad jur\u00eddica, que es \u00abuna<b> buena soluci\u00f3n para las familias\u00bb para proteger a la persona mayor<\/b> y \u00abfacilitar la vida ordinaria\u00bb.<\/p>\n<p>Segarra detalla que est\u00e1 pendiente de ampliar el plazo para revisar las medidas en relaci\u00f3n con la capacidad jur\u00eddica de las personas con discapacidad, pues <b>hay m\u00e1s de 108.000 casos pendientes de resolver<\/b> y el plazo terminaba en septiembre.<\/p>\n<p>La idea es \u00abintroducir una enmienda\u00bb en el proyecto de ley que est\u00e1 en estado de tramitaci\u00f3n \u00abpara hacer una ampliaci\u00f3n de ese plazo por tres a\u00f1os m\u00e1s\u00bb, una cuesti\u00f3n importante para<b> evitar \u00abuna merma de derechos en las personas\u00bb<\/b> porque es necesario el cambio de interpretaci\u00f3n de \u00ablas antiguas tutelas, las antiguas patrias potestades prorrogadas\u00bb que deben interpretarse de acuerdo a la nueva ley.<\/p>\n<p>\u00ab<b>No existe ya esa tutela para todo<\/b>, no existe ya esa patria potestad y yo decido hasta la ropa que te pones porque se tienen que interpretar como curatelas de acuerdo con los nuevos criterios de la ley, pero eso no quita para que evidentemente haya distintas velocidades, personas que ya tienen su traje con arreglo a los nuevos principios y quienes todav\u00eda no\u00bb, declara.<\/p>\n<p>En todo caso, \u00ab<b>la pr\u00f3rroga es necesaria<\/b>\u00bb porque faltan tres a\u00f1os y cuatro meses en un c\u00e1lculo aritm\u00e9tico para resolver los casos pendientes a pesar de que est\u00e1n en \u00abuna velocidad de crucero este a\u00f1o incre\u00edble\u00bb y este a\u00f1o se han resuelto un 50 % m\u00e1s de expedientes que el a\u00f1o anterior.<\/p>\n<p>Otra cuesti\u00f3n que suscita <b>dudas en materia de dependencia <\/b>se refiere a la de menores tutelados por las comunidades aut\u00f3nomas, pues su situaci\u00f3n cambia en cuanto llegan a la mayor\u00eda de edad.<\/p>\n<p>\u00abNo tiene por qu\u00e9 haber un vac\u00edo porque se puede prevenir\u00bb, desarrolla y dice que son casos tanto para menores que est\u00e1n bajo la tutela de una entidad p\u00fablica como otros que est\u00e1n con sus padres y a partir de los 16 a\u00f1os pueden acudir a un notario y <b>dise\u00f1ar un programa de apoyos y asistencial<\/b>, pues esta debe continuar al margen del posible expediente de apoyos para la capacidad jur\u00eddica.<\/p>\n<\/div>\n<p>Fuente: Discapacidad https:\/\/www.20minutos.es\/noticia\/5521398\/0\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Jos\u00e9 Segarra, fiscal y coordinadora de atenci\u00f3n a las personas con discapacidad y a los mayores, ha pedido una pr\u00f3rroga para revisar las medidas en relaci\u00f3n con la capacidad jur\u00eddica de las personas con discapacidad.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8],"tags":[],"class_list":["post-10109","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fiscal\u00eda pide ayuda para que no haya &quot;voluntades cautivas&quot; entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fiscal\u00eda pide ayuda para que no haya &quot;voluntades cautivas&quot; entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"og:description\" content=\"Mar\u00eda Jos\u00e9 Segarra, fiscal y coordinadora de atenci\u00f3n a las personas con discapacidad y a los mayores, ha pedido una pr\u00f3rroga para revisar las medidas en relaci\u00f3n con la capacidad jur\u00eddica de las personas con discapacidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionsindromecharge\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T05:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Charge\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:site\" content=\"@sindromecharge\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Charge\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/\"},\"author\":{\"name\":\"Charge\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"headline\":\"La Fiscal\u00eda pide ayuda para que no haya \u00abvoluntades cautivas\u00bb entre las personas mayores que est\u00e9n a cargo de cuidadores\",\"datePublished\":\"2024-06-17T05:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/\"},\"wordCount\":908,\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/\",\"name\":\"La Fiscal\u00eda pide ayuda para que no haya \\\"voluntades cautivas\\\" entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\"},\"datePublished\":\"2024-06-17T05:57:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/2024\\\/06\\\/17\\\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sindromecharge.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiscal\u00eda pide ayuda para que no haya &#8220;voluntades cautivas&#8221; entre las personas mayores que est\u00e9n a cargo de cuidadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#website\",\"url\":\"https:\\\/\\\/sindromecharge.es\\\/\",\"name\":\"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sindromecharge.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sindromecharge.es\\\/#\\\/schema\\\/person\\\/39a60ebe0a2b4d5a11179701e336b039\",\"name\":\"Charge\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x\",\"caption\":\"Charge\"},\"url\":\"https:\\\/\\\/sindromecharge.es\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fiscal\u00eda pide ayuda para que no haya \"voluntades cautivas\" entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/","og_locale":"es_ES","og_type":"article","og_title":"La Fiscal\u00eda pide ayuda para que no haya \"voluntades cautivas\" entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","og_description":"Mar\u00eda Jos\u00e9 Segarra, fiscal y coordinadora de atenci\u00f3n a las personas con discapacidad y a los mayores, ha pedido una pr\u00f3rroga para revisar las medidas en relaci\u00f3n con la capacidad jur\u00eddica de las personas con discapacidad.","og_url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/","og_site_name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","article_publisher":"https:\/\/www.facebook.com\/asociacionsindromecharge","article_published_time":"2024-06-17T05:57:02+00:00","og_image":[{"width":300,"height":98,"url":"https:\/\/sindromecharge.es\/wp-content\/uploads\/2013\/09\/logodecharge300x98.png","type":"image\/png"}],"author":"Charge","twitter_card":"summary_large_image","twitter_creator":"@sindromecharge","twitter_site":"@sindromecharge","twitter_misc":{"Escrito por":"Charge","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/#article","isPartOf":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/"},"author":{"name":"Charge","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"headline":"La Fiscal\u00eda pide ayuda para que no haya \u00abvoluntades cautivas\u00bb entre las personas mayores que est\u00e9n a cargo de cuidadores","datePublished":"2024-06-17T05:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/"},"wordCount":908,"articleSection":["noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/","url":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/","name":"La Fiscal\u00eda pide ayuda para que no haya \"voluntades cautivas\" entre las personas mayores que est\u00e9n a cargo de cuidadores - Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","isPartOf":{"@id":"https:\/\/sindromecharge.es\/#website"},"datePublished":"2024-06-17T05:57:02+00:00","author":{"@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039"},"breadcrumb":{"@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sindromecharge.es\/index.php\/2024\/06\/17\/maltrato-mayores-entrevista-fiscalia-pide-ayuda-para-que-no-haya-voluntades-cautivas-entre-las-personas-mayores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sindromecharge.es\/"},{"@type":"ListItem","position":2,"name":"La Fiscal\u00eda pide ayuda para que no haya &#8220;voluntades cautivas&#8221; entre las personas mayores que est\u00e9n a cargo de cuidadores"}]},{"@type":"WebSite","@id":"https:\/\/sindromecharge.es\/#website","url":"https:\/\/sindromecharge.es\/","name":"Asociaci\u00f3n Espa\u00f1ola S\u00edndrome de Charge","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sindromecharge.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sindromecharge.es\/#\/schema\/person\/39a60ebe0a2b4d5a11179701e336b039","name":"Charge","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","url":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c3b46e32a0fc3b093a0873fb767bf3293de856293065e84ef06b7ec7a8acfb98?s=96&d=identicon&r=x","caption":"Charge"},"url":"https:\/\/sindromecharge.es\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/comments?post=10109"}],"version-history":[{"count":0,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/posts\/10109\/revisions"}],"wp:attachment":[{"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/media?parent=10109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/categories?post=10109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindromecharge.es\/index.php\/wp-json\/wp\/v2\/tags?post=10109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}